{"id":11455,"date":"2025-10-21T16:17:47","date_gmt":"2025-10-21T16:17:47","guid":{"rendered":"https:\/\/frijobel.pt\/?p=11455"},"modified":"2025-10-21T16:17:47","modified_gmt":"2025-10-21T16:17:47","slug":"departamento-de-producao-reforcado","status":"publish","type":"post","link":"https:\/\/frijobel.pt\/pt\/departamento-de-producao-reforcado\/","title":{"rendered":"Departamento de Produ\u00e7\u00e3o refor\u00e7ado"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-equal-height vc_row-flex\" ><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768 edgtf-one-column-alignment-center\" ><div class=\"edgtf-eh-item  edgtf-vertical-alignment-top edgtf-horizontal-alignment-center \"  data-item-class=\"edgtf-eh-custom-5307\" data-1367-1600=\"0px 5% 0 5%\" data-1025-1366=\"0px 5% 0 5%\"   >\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-5307\" >\n\t\t\t<div class=\"edgtf-image-gallery  edgtf-ig-slider-type edgtf-three-columns edgtf-huge-space  edgtf-image-behavior-lightbox\">\n\t<div class=\"edgtf-ig-slider edgtf-owl-slider\" data-number-of-items=\"1\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-slider-padding=\"no\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"edgtf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"edgtf-ig-lightbox edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2025\/10\/2.png\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-207]\" title=\"2\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2025\/10\/2-1024x576.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2025\/10\/2-1024x576.png 1024w, https:\/\/frijobel.pt\/wp-content\/uploads\/2025\/10\/2-300x169.png 300w, https:\/\/frijobel.pt\/wp-content\/uploads\/2025\/10\/2-768x432.png 768w, https:\/\/frijobel.pt\/wp-content\/uploads\/2025\/10\/2-1536x864.png 1536w, https:\/\/frijobel.pt\/wp-content\/uploads\/2025\/10\/2-18x10.png 18w, https:\/\/frijobel.pt\/wp-content\/uploads\/2025\/10\/2-600x338.png 600w, https:\/\/frijobel.pt\/wp-content\/uploads\/2025\/10\/2.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768 \" ><div class=\"edgtf-eh-item    \"  data-item-class=\"edgtf-eh-custom-6628\" data-1367-1600=\"-10px 5% 0 5%\" data-1025-1366=\"-10px 5% 0 5%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-6628\" style=\"padding: 0 0 0 0\">\n\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span data-teams=\"true\">Conclu\u00edmos a \u00faltima fase da reorganiza\u00e7\u00e3o do layout da nossa sala de Produ\u00e7\u00e3o. Esta mudan\u00e7a permitiu-nos dar mais um passo em frente: inici\u00e1mos a embalagem de produtos em sacos com pesos de 500g ou inferiores &#8211; ideais para pe\u00e7as mais pequenas, como miolos.<br \/>\nInstal\u00e1mos tamb\u00e9m uma nova serra autom\u00e1tica, que realiza cortes de forma totalmente aut\u00f3noma, necessitando apenas de um operador para alimenta\u00e7\u00e3o da m\u00e1quina. Esta aquisi\u00e7\u00e3o permite-nos aumentar a quantidade de produto cortado por dia, com mais efici\u00eancia e rentabilidade, ao mesmo tempo que reduz drasticamente o risco de corte e os acidentes de trabalho.<br \/>\nCom estas &#8211; e outras &#8211; melhorias no espa\u00e7o e nos processos, estamos cada vez mais pr\u00f3ximos das metas definidas pela Dire\u00e7\u00e3o Operacional para este ano, especialmente no que toca ao aumento do volume de produ\u00e7\u00e3o di\u00e1rio.<br \/>\nHoje, a nossa Produ\u00e7\u00e3o est\u00e1 mais moderna, mais eficiente e pronta para os desafios que a\u00ed v\u00eam.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Aumento da Capacidade Log\u00edstica da Frijobel.<\/p>\n","protected":false},"author":20,"featured_media":11457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[479],"tags":[965,824,493],"class_list":["post-11455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-965","tag-frijobel","tag-producao"],"_links":{"self":[{"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/posts\/11455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/comments?post=11455"}],"version-history":[{"count":1,"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/posts\/11455\/revisions"}],"predecessor-version":[{"id":11458,"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/posts\/11455\/revisions\/11458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/media\/11457"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/media?parent=11455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/categories?post=11455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frijobel.pt\/pt\/wp-json\/wp\/v2\/tags?post=11455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}