{"id":5454,"date":"2020-11-20T00:24:36","date_gmt":"2020-11-20T00:24:36","guid":{"rendered":"http:\/\/www.frijobel.pt\/novo\/?post_type=product&#038;p=5454"},"modified":"2021-06-08T14:44:07","modified_gmt":"2021-06-08T14:44:07","slug":"lagostim","status":"publish","type":"product","link":"https:\/\/frijobel.pt\/it\/product\/lagostim\/","title":{"rendered":"SCAMPO"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"edgtf-row-grid-section-wrapper\"  style=\"background-color:#ffffff\"><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1607202604637 vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-8866\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-8866\" style=\"padding: 3% 0 0 2%\">\n\t\t\t<div class=\"edgtf-portfolio-slider-holder\"><div class=\"edgtf-portfolio-list-holder edgtf-grid-list edgtf-disable-bottom-space edgtf-pl-gallery edgtf-four-columns edgtf-tiny-space edgtf-pl-standard-tilt    edgtf-pl-pag-no-pagination    edgtf-pl-info-skin-light edgtf-pag-below-slider  light\"  data-type=\"gallery\" data-number-of-columns=\"four\" data-space-between-items=\"tiny\" data-number-of-items=\"-1\" data-image-proportions=\"square\" data-enable-fixed-proportions=\"no\" data-enable-image-shadow=\"no\" data-category=\"receitas-frijobel\" data-tag=\"marisco\" data-orderby=\"title\" data-order=\"ASC\" data-item-style=\"standard-tilt\" data-enable-title=\"yes\" data-title-tag=\"h4\" data-title-text-transform=\"uppercase\" data-enable-category=\"no\" data-enable-count-images=\"yes\" data-enable-excerpt=\"yes\" data-excerpt-length=\"65\" data-pagination-type=\"no-pagination\" data-filter=\"no\" data-filter-order-by=\"name\" data-enable-article-animation=\"no\" data-portfolio-slider-on=\"yes\" data-enable-fullheight=\"no\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"yes\" data-pagination-skin=\"light\" data-info-skin=\"light\" data-pagination-position=\"below-slider\" data-max-num-pages=\"0\" data-next-page=\"2\">\n\t\t<div class=\"edgtf-pl-inner edgtf-outer-space edgtf-owl-slider edgtf-list-is-slider clearfix\">\n\t\t<article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-3862 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/08\/acorda_camaroes_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"A\u00e7orda Camar\u00f5es Thumbs\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">A\u00c7ORDA (PAN COTTO SPECIALE) DI GAMBERI<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 35 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/acorda-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-3873 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-bacalhau portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/08\/acorda_ovas_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"A\u00e7orda de ovas com camar\u00e3o\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tA\u00c7ORDA (PAN COTTO SPECIALE) CON UOVA DI MERLUZZO NORDICO DE OVAS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 45 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/acorda-de-ovas\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-10269 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-ameijoa portfolio-tag-camarao portfolio-tag-delicias portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"505\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2022\/05\/3-550x505.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tARROZ DE MARISCO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Prato Principal | 40min | 2 pessoas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/arroz-de-marisco\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-3888 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-camarao-vannamei portfolio-tag-carne portfolio-tag-mar-e-terra portfolio-tag-marisco portfolio-tag-molho portfolio-tag-prato-principal portfolio-tag-queijo portfolio-tag-shrimp portfolio-tag-vannamei portfolio-tag-vitela\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/08\/vitela_queijo_camarao_thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"Vitela com queijo e camar\u00e3o\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tBISTECCA DI VITELLO CON SALSA AL FORMAGGIO E GAMBERI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 50 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/bife-vitela-queijo-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5136 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-caldeirada portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/caldeirada_de_peixe2-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSTUFATO DI PESCE E GAMBERI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 50 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/caldeirada-peixe-camaroes-black-tiger\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5760 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/camarao_agricode-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tGAMBERI AGRODOLCE CON SPAGHETTI DI RISO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 40 min | 2 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/camarao-com-massa\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5773 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/camarao-na-chapa-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">GAMBERONI ALLA PIASTRA<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 20 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/camarao-na-chapa\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5783 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco portfolio-tag-pre-cozinhados\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/camarao-wiskey_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">GAMBERETTI FRITTI<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 2h20min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/camaroes-fritos\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5793 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/camaroes-grelhados_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tGAMBERI ALLA GRIGLIA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">1h15min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/camaroes-grelhados\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5807 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/caril-peixe-marisco_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\"><span class=\"edgtf-st-title-bold\">PESCE E <\/span> <span class=\"edgtf-st-title-bold\">FRUTTI DI MARE<\/span> <span class=\"edgtf-st-title-bold\"> AL CURRY<\/span><\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 40 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/caril-de-peixe\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5820 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/cascata-camara-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">CASCATA DI GAMBERI<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 25 min | 3 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/cascata-de-camaroes\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5836 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-cebola portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/cataplana_chocos-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">STUFATO DI SEPPIA<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 1h50min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/cataplana-de-chocos\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5845 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/cataplana_tamboril_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">STUFATO DI RANA PESCATRICE<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 1h50min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/cataplana-de-tamboril\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5891 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-frango portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/chowmein_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCHOW MEIN ALLE 3 DELIZIE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 2h25min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/chow-mein-tres-delicias\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5924 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/cocktail-camarao-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCOCKTAIL DI GAMBERI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 20 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/cocktail-de-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5933 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-frango portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/codorniz_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">QUAGLIA AL SIDRO<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 2h45min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/codorniz-com-sidra\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5945 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/costeleta-vitela-grlehada_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">COSTATA DI VITELLO ALLA GRIGLIA<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 45 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/costeleta-de-vitela\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5962 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/creeme-camarao_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCREMA DI GAMBERI CON WHISKY\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Minestra | 45min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/creme-de-camarao-com-whisky\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6026 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-feijao portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/feijoada-camarao-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFAGIOLATA DI GAMBERI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 30 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/feijoada-de-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6043 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/feijoada-choco-camarao_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFAGIOLATA DI SEPPIA CON GAMBERI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 35 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/feijoada-de-choco-e-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6054 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-feijao portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/feijoada-peixe-camarao_thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFAGIOLATA DI PESCE E FRUTTI DI MARE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 50 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/feijoada-de-peixe-e-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6059 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/fetuccine-camaroes_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFETTUCCINE ALLE VONGOLE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 1h10min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/fettuccine-com-ameijoas-e-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6095 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-frango portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pato portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/frango-camarao-leitecoco_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">POLLO CON GAMBERI<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 55 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/frango-com-camaroes\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6104 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/gratinado-marisco-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tGRATIN DI FRUTTI DI MARE CON PORRO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 45 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/gratinado-de-marisco-e-alho-frances\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6115 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/rejardineira-chocos_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSEPPIA E GAMBERI CON VERDURE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 35 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/jardineira-de-choco-e-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6125 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-sopa\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/korma-camarao_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tKORMA DI GAMBERI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Minestra | 45min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/korma-de-camarao-com-garam-massala\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6138 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-entradas portfolio-tag-marisco\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/lapas-picantes_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPATELLE PICCANTI CON BURRO ALL'AGLIO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 25 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/lapas-picantes-com-manteiga-de-alho\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-10288 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-ameijoa portfolio-tag-camarao portfolio-tag-delicias portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"505\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2022\/05\/1-2-550x505.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tMARISCADA PICANTE \u00c0 BULH\u00c3O PATO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Prato Principal | 30min | 2 pessoas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/mariscada-picante\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6156 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/maruca-exotico_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tABADECO CON SALSA ESOTICA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 50 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/maruca-com-molho-exotico\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6176 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/massada-chocos-camaroes_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPASTA CON SEPPIA E GAMBERI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 30 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/massada-de-chocos-com-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6186 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/massada-marisco-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPASTA AI FRUTTI DI MARE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 20 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/massada-de-marisco-tradicional\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6202 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-caldeirada portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/moqueca-de-peixe_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tMOQUECA DI PESCE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 55 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/moqueca-de-peixe\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6231 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-posta portfolio-tag-prato-principal portfolio-tag-tomate\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/peixe-estufado_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSTUFATO DI PESCE CON VONGOLE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 55 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/peixe-estufado-com-ameijoas\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6237 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-posta portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/pescada-marujo_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tNASELLO ALLA MARINARA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 35min | 3 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/pescada-a-marujo\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-10276 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-ameijoa portfolio-tag-camarao portfolio-tag-delicias portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"505\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2022\/05\/1-1-550x505.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPIZZA DE FRUTOS DO MAR\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 30 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/pizza-de-frutos-do-mar\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6319 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-entrada portfolio-tag-marisco portfolio-tag-pastelaria portfolio-tag-pre-cozinhado\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/quiche-marisco_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">QUICHE AI FRUTTI DI MARE<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 1h10min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/quiche-de-marisco\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6330 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-camarao-black-tiger portfolio-tag-delicias portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pimento portfolio-tag-prato-principal portfolio-tag-pre-cozinhado portfolio-tag-sapateira\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/quinoa-marisco_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tQUINOA CON FRUTTI DI MARE E BABY PEPERONI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 35 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/quinoa-com-marisco-e-mini-pimentos\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-10407 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-lagostim portfolio-tag-marisco portfolio-tag-prato-principal portfolio-tag-risotto\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"501\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2022\/08\/Sem-Titulo-550x501.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tRISOTTO DE LAGOSTIM\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Prato Principal | 1h e 15min | 2 pessoas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/risotto-lagostim\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6347 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-delicias portfolio-tag-marisco portfolio-tag-prato-principal portfolio-tag-sapateira\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/risoto_marsico_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tRISOTTO AI FRUTTI DI MARE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 45 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/risotto-de-marisco\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6357 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-delicias portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal portfolio-tag-sapateira\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/risotto-sapateira_thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">RISOTTO AL GRANCIPORRO<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 55 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/risotto-de-sapateira\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6382 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-cogumelos portfolio-tag-entradas portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-salada\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/salada-morna_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">INSALATA TIEPIDA DI GAMBERI<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Insalata | 1h10min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/salada-morna-de-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6530 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco portfolio-tag-sapateira\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sapateira_gratinada_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">GRANCIPORRO GRATINATO<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 35 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/sapateira-gratinada\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6590 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco portfolio-tag-sapateira\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sapateira_recheada_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\"><span class=\"edgtf-st-title-bold\">GRANCIPORRO <\/span> <span class=\"edgtf-st-title-bold\">RIPIENO<\/span><\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 35 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/sapateira-recheada\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6601 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco portfolio-tag-sapateira\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sapateira-recheadao-cocktail_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tGRANCIPORRO RIPIENO CON SALSA COCKTAIL\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 35 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/sapateira-recheada-com-molho-cocktail\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6610 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco portfolio-tag-sapateira\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sapateira-recheada-especial_crop_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tGRANCIPORRO RIPIENO SPECIALE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 35 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/sapateira-recheada-especial\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6658 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-marisco portfolio-tag-pescada portfolio-tag-pescado portfolio-tag-posta portfolio-tag-solha portfolio-tag-sopa\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sopa-peixe_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tZUPPA CREMOSA DI PESCE E GAMBERI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Minestra | 45min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/sopa-de-peixe-e-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>NOME SCIENTIFICO: <\/strong>Nephrops norvegicus<br \/>\n<strong>ORIGINE:<\/strong> Atlantico del Nord, Mare del Nord<strong><br \/>\nPEZZATURA:\u00a0<\/strong> 21\/30, 8\/12<br \/>\n<strong>PRESENTAZIONE:\u00a0<\/strong> Intero<br \/>\n<strong>IMBALLAGGIO: <\/strong>Vaschetta<\/p>","protected":false},"featured_media":9935,"template":"","meta":[],"product_brand":[],"product_cat":[283],"product_tag":[391,338,597,301],"class_list":{"0":"post-5454","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-marisco-bivalves","7":"product_tag-crustaceos","8":"product_tag-lagosta","9":"product_tag-lagostim","10":"product_tag-marisco","12":"first","13":"instock","14":"shipping-taxable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/product\/5454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/media\/9935"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/media?parent=5454"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/product_brand?post=5454"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/product_cat?post=5454"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/product_tag?post=5454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}