{"id":5104,"date":"2020-11-14T01:05:18","date_gmt":"2020-11-14T01:05:18","guid":{"rendered":"http:\/\/www.frijobel.pt\/novo\/?page_id=5104"},"modified":"2024-10-08T11:23:45","modified_gmt":"2024-10-08T11:23:45","slug":"produtos","status":"publish","type":"page","link":"https:\/\/frijobel.pt\/it\/produtos\/","title":{"rendered":"PRODOTTI"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parallax-bg-image=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/produtos.jpg\" data-parallax-bg-speed=\"1\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1612523199598 vc_row-has-fill vc_row-o-full-height vc_row-o-columns-middle vc_row-flex edgtf-parallax-row-holder\" style=\"background-color:rgba(0,0,0,0.53)\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1595259860121\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item   edgtf-horizontal-alignment-center\"  data-item-class=\"edgtf-eh-custom-4821\" data-769-1024=\"60% 0 50% 0\" data-681-768=\"50% 0 70% 0\" data-680=\"83% 0 80% 0\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-4821\" >\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-center edgtf-st-normal-space\" style=\"padding: 0 10%\">\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h1 class=\"edgtf-st-title\" style=\"color: #ffffff\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">PRODOTTI<\/span>\t\t\t<\/h1>\n\t\t\t\t\t\t\t<p class=\"edgtf-st-text\" style=\"color: #ffffff;font-size: 22px;font-weight: 400\">\n\t\t\t\tGAMMA COMPLETA FRIJOBEL\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"edgtf-row-grid-section-wrapper\"  ><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1607396239170 vc_row-o-full-height vc_row-o-columns-middle vc_row-flex\" ><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 42px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item   edgtf-horizontal-alignment-right\"  data-item-class=\"edgtf-eh-custom-4186\" data-1367-1600=\"3% 3px 1% 0\" data-1025-1366=\"3% 3px 1% 0\" data-769-1024=\"0 0 3% 0\" data-681-768=\"0 0 3% 0\" data-680=\"0 0 5% 0\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-4186\" style=\"padding: 3% 3px 1% 0\">\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-right edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title translation-block\" style=\"color: #494949\">LA NOSTRA GAMMA DI PRODOTTI<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item   edgtf-horizontal-alignment-right\"  data-item-class=\"edgtf-eh-custom-6434\" data-1367-1600=\"3% 3px 3% 0\" data-1025-1366=\"3% 3px 3% 0\" data-769-1024=\"3% 0 3% 0\" data-681-768=\"5% 0 3% 0\" data-680=\"5% 0 5% 0\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-6434\" style=\"padding: 3% 3px 3% 0\">\n\t\t\t<a itemprop=\"url\" href=\"https:\/\/frijobel.pt\/web\/wp-content\/uploads\/2024\/05\/FRIJOBEL_Catalogo-pt-en-2024\u00ae_compressed-1.pdf\" target=\"_blank\" style=\"color: #494949;font-weight: 500;text-transform: uppercase\" class=\"edgtf-btn edgtf-btn-medium edgtf-btn-simple edgtf-btn-custom-hover-color edgtf-btn-icon\" data-hover-color=\"#f49200\" >\n    <span class=\"edgtf-btn-text\">Cat\u00e1logo Digital - PT | EN<\/span>\n    <span aria-hidden=\"true\" class=\"edgtf-icon-font-elegant icon_plus_alt\" ><\/span><\/a><div class=\"vc_empty_space\"   style=\"height: 3px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><a itemprop=\"url\" href=\"https:\/\/frijobel.pt\/web\/wp-content\/uploads\/2024\/05\/FRIJOBEL_Catalogo-ing-fr-2024\u00ae_compressed.pdf\" target=\"_blank\" style=\"color: #494949;font-weight: 500;text-transform: uppercase\" class=\"edgtf-btn edgtf-btn-medium edgtf-btn-simple edgtf-btn-custom-hover-color edgtf-btn-icon\" data-hover-color=\"#f49200\" >\n    <span class=\"edgtf-btn-text\">Cat\u00e1logo Digital - EN | FR<\/span>\n    <span aria-hidden=\"true\" class=\"edgtf-icon-font-elegant icon_plus_alt\" ><\/span><\/a>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"woocommerce columns-4\"><ul class=\"products columns-4\">\n<li class=\"product-category product first\">\n\t<a aria-label=\"Visita categoria del prodotto Pescado\" href=\"https:\/\/frijobel.pt\/it\/product-category\/pescado\/\" data-no-translation-aria-label=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/pescado_family_pic-400x300.jpg\" alt=\"Pescado\" width=\"400\" height=\"300\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tPescato <mark class=\"count\">(39)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<li class=\"product-category product\">\n\t<a aria-label=\"Visita categoria del prodotto Marisco e Bivalves\" href=\"https:\/\/frijobel.pt\/it\/product-category\/marisco-bivalves\/\" data-no-translation-aria-label=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/MARISCO-400x300.jpg\" alt=\"Marisco e Bivalves\" width=\"400\" height=\"300\" srcset=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/MARISCO-400x300.jpg 400w, https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/MARISCO-397x298.jpg 397w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tFrutti di mare e bivalvi <mark class=\"count\">(20)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<li class=\"product-category product\">\n\t<a aria-label=\"Visita categoria del prodotto Cefal\u00f3podes\" href=\"https:\/\/frijobel.pt\/it\/product-category\/cefalopodes\/\" data-no-translation-aria-label=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/cefalopodes-categoria-400x300.jpg\" alt=\"Cefal\u00f3podes\" width=\"400\" height=\"300\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tCefalopodi <mark class=\"count\">(8)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<li class=\"product-category product last\">\n\t<a aria-label=\"Visita categoria del prodotto Carnes\" href=\"https:\/\/frijobel.pt\/it\/product-category\/carnes\/\" data-no-translation-aria-label=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/CARNES-400x300.jpg\" alt=\"Carnes\" width=\"400\" height=\"300\" srcset=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/CARNES-400x300.jpg 400w, https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/CARNES-397x298.jpg 397w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tCarne <mark class=\"count\">(24)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<li class=\"product-category product first\">\n\t<a aria-label=\"Visita categoria del prodotto Batatas\" href=\"https:\/\/frijobel.pt\/it\/product-category\/batatas\/\" data-no-translation-aria-label=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/07\/batatas_categoria-400x300.jpg\" alt=\"Batatas\" width=\"400\" height=\"300\" srcset=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/07\/batatas_categoria-400x300.jpg 400w, https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/07\/batatas_categoria-300x225.jpg 300w, https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/07\/batatas_categoria-768x576.jpg 768w, https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/07\/batatas_categoria-16x12.jpg 16w, https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/07\/batatas_categoria-600x450.jpg 600w, https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/07\/batatas_categoria.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tPATATE <mark class=\"count\">(8)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<li class=\"product-category product\">\n\t<a aria-label=\"Visita categoria del prodotto Legumes\" href=\"https:\/\/frijobel.pt\/it\/product-category\/legumes\/\" data-no-translation-aria-label=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/legumes-400x300.jpg\" alt=\"Legumes\" width=\"400\" height=\"300\" srcset=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/legumes-400x300.jpg 400w, https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/legumes-397x298.jpg 397w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tVerdure <mark class=\"count\">(20)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<li class=\"product-category product\">\n\t<a aria-label=\"Visita categoria del prodotto Doces\" href=\"https:\/\/frijobel.pt\/it\/product-category\/doces\/\" data-no-translation-aria-label=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/07\/pastel_de_nata_hero-400x300.jpg\" alt=\"Doces\" width=\"400\" height=\"300\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tDOLCI <mark class=\"count\">(3)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<li class=\"product-category product last\">\n\t<a aria-label=\"Visita categoria del prodotto Pr\u00e9-cozinhados\" href=\"https:\/\/frijobel.pt\/it\/product-category\/pre-cozinhados\/\" data-no-translation-aria-label=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/pre-cozinhados-400x300.jpg\" alt=\"Pr\u00e9-cozinhados\" width=\"400\" height=\"300\" srcset=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/pre-cozinhados-400x300.jpg 400w, https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/07\/pre-cozinhados-397x298.jpg 397w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tPRECOTTI <mark class=\"count\">(26)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1605316696688 vc_row-no-padding vc_row-o-full-height vc_row-o-columns-middle vc_row-o-content-middle vc_row-flex\" style=\"background-color:#f2f2f2\"><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-center edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title\" style=\"color: #494949\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">RICETTE<\/span> <span class=\"edgtf-st-title-light\">DELIZIOSE<\/span>\t\t\t<\/h2>\n\t\t\t\t\t\t\t<p class=\"edgtf-st-text\" >\n\t\t\t\tI SAPORI UNICI DI FRIJOBEL\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-portfolio-slider-holder\"><div class=\"edgtf-portfolio-list-holder edgtf-grid-list edgtf-disable-bottom-space edgtf-pl-gallery edgtf-four-columns edgtf-tiny-space edgtf-pl-standard-tilt    edgtf-pl-pag-no-pagination    edgtf-pl-info-skin-light edgtf-pag-below-slider  light\"  data-type=\"gallery\" data-number-of-columns=\"four\" data-space-between-items=\"tiny\" data-number-of-items=\"11\" data-image-proportions=\"square\" data-enable-fixed-proportions=\"no\" data-enable-image-shadow=\"no\" data-category=\"receitas-frijobel\" data-orderby=\"menu_order\" data-order=\"ASC\" data-item-style=\"standard-tilt\" data-enable-title=\"yes\" data-title-tag=\"h4\" data-title-text-transform=\"uppercase\" data-enable-category=\"no\" data-enable-count-images=\"yes\" data-enable-excerpt=\"yes\" data-excerpt-length=\"65\" data-pagination-type=\"no-pagination\" data-filter=\"no\" data-filter-order-by=\"name\" data-enable-article-animation=\"no\" data-portfolio-slider-on=\"yes\" data-enable-fullheight=\"no\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"yes\" data-pagination-skin=\"light\" data-info-skin=\"light\" data-pagination-position=\"below-slider\" data-max-num-pages=\"11\" data-next-page=\"2\">\n\t\t<div class=\"edgtf-pl-inner edgtf-outer-space edgtf-owl-slider edgtf-list-is-slider clearfix\">\n\t\t<article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6630 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato portfolio-tag-principal portfolio-tag-sardinha portfolio-tag-tomate\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sardinha_tomatada_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSARDINE AL POMODORO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 2h20min | 2 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/sardinhas-de-tomatada\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5856 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/choco-lagareiro_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSEPPIA ALLA LAGAREIRO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 1h30min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/choco-a-lagareiro\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6618 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato portfolio-tag-principal portfolio-tag-sardinha\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sardinha-a-lagareiro_thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">SARDINE ALLA LAGAREIRO<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 2h30min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/sardinhas-a-lagareiro\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6194 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-entrada portfolio-tag-legumes\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/mexilhoes-a-francesa-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCOZZE ALLA FRANCESE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 20 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/mexilhoes-a-francesa\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6658 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-marisco portfolio-tag-pescada portfolio-tag-pescado portfolio-tag-posta portfolio-tag-solha portfolio-tag-sopa\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sopa-peixe_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tZUPPA CREMOSA DI PESCE E GAMBERI\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Minestra | 45min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/sopa-de-peixe-e-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-10378 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-choco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"501\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2022\/08\/site1-550x501.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCHOCO ASSADO COM BATATAS \u00c0 MURRO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 1h30 min | 3 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/choco-batata-murro\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-11271 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-caldeirada portfolio-tag-caldeirada-de-raia portfolio-tag-prato-principal portfolio-tag-raia portfolio-tag-receitas\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/08\/Icon-receitas-550x506-1.png\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/08\/Icon-receitas-550x506-1.png 550w, https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/08\/Icon-receitas-550x506-1-300x276.png 300w, https:\/\/frijobel.pt\/wp-content\/uploads\/2024\/08\/Icon-receitas-550x506-1-13x12.png 13w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCALDEIRADA DE RAIA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Prato principal | 1h | 3 pessoas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/caldeirada-de-raia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5773 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-entradas portfolio-tag-marisco\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/camarao-na-chapa-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">GAMBERONI ALLA PIASTRA<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Antipasto | 20 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/camarao-na-chapa\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5875 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/choco-assado_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSEPPIE AL FORNO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 2h30min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/choco-assado\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6036 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-feijao portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/feijoada-chocos-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">FAGIOLATA DI SEPPIA<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 25 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/feijoada-de-choco\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6202 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-caldeirada portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/moqueca-de-peixe_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tMOQUECA DI PESCE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Piatto principale | 55 min | 4 persone<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/it\/portfolio-item\/moqueca-de-peixe\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 40px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"MOQUECA DE PEIXE Prato Principal 55min 4 pessoas NOSSOS PRODUTOS Leggi tutto CALDEIRADA DE PEIXE Pescado Leggi tutto CEBOLA Legumes Leggi tutto PIMENTO Legumes Leggi tutto TOMATE Legumes INGREDIENTES 1 embalagem de mistura para caldeirada de [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-5104","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/pages\/5104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/comments?post=5104"}],"version-history":[{"count":8,"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/pages\/5104\/revisions"}],"predecessor-version":[{"id":11306,"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/pages\/5104\/revisions\/11306"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/it\/wp-json\/wp\/v2\/media?parent=5104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}