{"id":3531,"date":"2020-07-10T01:04:33","date_gmt":"2020-07-10T01:04:33","guid":{"rendered":"http:\/\/www.frijobel.pt\/novo\/?post_type=product&#038;p=3531"},"modified":"2020-12-06T20:39:56","modified_gmt":"2020-12-06T20:39:56","slug":"entrecosto-de-porco","status":"publish","type":"product","link":"https:\/\/frijobel.pt\/fr\/product\/entrecosto-de-porco\/","title":{"rendered":"TRAVERS DE PORC"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"edgtf-row-grid-section-wrapper\"  style=\"background-color:#ffffff\"><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1607287168466 vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-3921\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-3921\" style=\"padding: 3% 0 0 0\">\n\t\t\t<div class=\"edgtf-portfolio-slider-holder\"><div class=\"edgtf-portfolio-list-holder edgtf-grid-list edgtf-disable-bottom-space edgtf-pl-gallery edgtf-four-columns edgtf-tiny-space edgtf-pl-standard-tilt    edgtf-pl-pag-no-pagination    edgtf-pl-info-skin-light edgtf-pag-below-slider  light\"  data-type=\"gallery\" data-number-of-columns=\"four\" data-space-between-items=\"tiny\" data-number-of-items=\"-1\" data-image-proportions=\"square\" data-enable-fixed-proportions=\"no\" data-enable-image-shadow=\"no\" data-category=\"receitas-frijobel\" data-tag=\"carne\" data-orderby=\"title\" data-order=\"ASC\" data-item-style=\"standard-tilt\" data-enable-title=\"yes\" data-title-tag=\"h4\" data-title-text-transform=\"uppercase\" data-enable-category=\"no\" data-enable-count-images=\"yes\" data-enable-excerpt=\"yes\" data-excerpt-length=\"65\" data-pagination-type=\"no-pagination\" data-filter=\"no\" data-filter-order-by=\"name\" data-enable-article-animation=\"no\" data-portfolio-slider-on=\"yes\" data-enable-fullheight=\"no\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"yes\" data-pagination-skin=\"light\" data-info-skin=\"light\" data-pagination-position=\"below-slider\" data-max-num-pages=\"0\" data-next-page=\"2\">\n\t\t<div class=\"edgtf-pl-inner edgtf-outer-space edgtf-owl-slider edgtf-list-is-slider clearfix\">\n\t\t<article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-3888 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-camarao-vannamei portfolio-tag-carne portfolio-tag-mar-e-terra portfolio-tag-marisco portfolio-tag-molho portfolio-tag-prato-principal portfolio-tag-queijo portfolio-tag-shrimp portfolio-tag-vannamei portfolio-tag-vitela\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/08\/vitela_queijo_camarao_thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"Vitela com queijo e camar\u00e3o\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSTEAK DE VEAU AVEC UNE SAUCE AU FROMAGE ET AUX CREVETTES\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 50 min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/bife-vitela-queijo-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5933 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-frango portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/codorniz_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">CAILLE AU CIDRE<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 2h45min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/codorniz-com-sidra\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5945 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/costeleta-vitela-grlehada_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">C\u00d4TELETTES DE VEAU GRILL\u00c9ES<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 45min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/costeleta-de-vitela\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-10944 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-entremeada portfolio-tag-leitao portfolio-tag-prato-principal portfolio-tag-receitas\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2023\/09\/Icon-receitas-550x506-4.png\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" srcset=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2023\/09\/Icon-receitas-550x506-4.png 550w, https:\/\/frijobel.pt\/wp-content\/uploads\/2023\/09\/Icon-receitas-550x506-4-300x276.png 300w, https:\/\/frijobel.pt\/wp-content\/uploads\/2023\/09\/Icon-receitas-550x506-4-13x12.png 13w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tENTREMEADA DE LEIT\u00c3O \u00c0 BAIRRADA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Prato principal | 2h | 3 pessoas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/entremeada-de-leitao-a-bairrada\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6083 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-carne portfolio-tag-frango portfolio-tag-legumes portfolio-tag-pato portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/frango-ameijoa-thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPOULET ET PALOURDES \u00c0 LA MODE DE L\u2019ALGARVE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 60min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/frango-com-ameijoas-a-algarvia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6095 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-frango portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pato portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/frango-camarao-leitecoco_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">POULET AUX CREVETTES<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 55min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/frango-com-camaroes\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6263 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/petinga-no-forno_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPETITES SARDINES (PETINGAS) AU FOUR AVEC DU BACON\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 1h25min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/petinga-no-forno-com-bacon\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6733 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-legumes portfolio-tag-maruca portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/tornedo-maruca-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tTOURNEDOS DE LINGUE AVEC DU BACON\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 2h15min | 3 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/tornedo-de-maruca-com-bacon\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>EMBALLAGE:<\/strong> Bo\u00eete<\/p>","protected":false},"featured_media":3448,"template":"","meta":[],"product_brand":[],"product_cat":[281],"product_tag":[331,347,337,334],"class_list":{"0":"post-3531","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-carnes","7":"product_tag-carnes","8":"product_tag-entrecosto","9":"product_tag-meats","10":"product_tag-porco","12":"first","13":"instock","14":"shipping-taxable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product\/3531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/media\/3448"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/media?parent=3531"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product_brand?post=3531"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product_cat?post=3531"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product_tag?post=3531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}