{"id":11123,"date":"2024-06-30T18:48:40","date_gmt":"2024-06-30T18:48:40","guid":{"rendered":"https:\/\/frijobel.pt\/website_96915706\/?post_type=product&#038;p=11123"},"modified":"2024-06-30T18:48:40","modified_gmt":"2024-06-30T18:48:40","slug":"batata-as-rodelas","status":"publish","type":"product","link":"https:\/\/frijobel.pt\/fr\/product\/batata-as-rodelas\/","title":{"rendered":"BATATA \u00c0S RODELAS"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"edgtf-row-grid-section-wrapper\"  style=\"background-color:#ffffff\"><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1607208827666 vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-1523\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-1523\" style=\"padding: 3% 0 0 2%\">\n\t\t\t<div class=\"edgtf-portfolio-slider-holder\"><div class=\"edgtf-portfolio-list-holder edgtf-grid-list edgtf-disable-bottom-space edgtf-pl-gallery edgtf-four-columns edgtf-tiny-space edgtf-pl-standard-tilt    edgtf-pl-pag-no-pagination    edgtf-pl-info-skin-light edgtf-pag-below-slider  light\"  data-type=\"gallery\" data-number-of-columns=\"four\" data-space-between-items=\"tiny\" data-number-of-items=\"-1\" data-image-proportions=\"square\" data-enable-fixed-proportions=\"no\" data-enable-image-shadow=\"no\" data-category=\"receitas-frijobel\" data-selected-projects=\"6083,6095,5933,5891\" data-orderby=\"title\" data-order=\"ASC\" data-item-style=\"standard-tilt\" data-enable-title=\"yes\" data-title-tag=\"h4\" data-title-text-transform=\"uppercase\" data-enable-category=\"no\" data-enable-count-images=\"yes\" data-enable-excerpt=\"yes\" data-excerpt-length=\"65\" data-pagination-type=\"no-pagination\" data-filter=\"no\" data-filter-order-by=\"name\" data-enable-article-animation=\"no\" data-portfolio-slider-on=\"yes\" data-enable-fullheight=\"no\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"yes\" data-pagination-skin=\"light\" data-info-skin=\"light\" data-pagination-position=\"below-slider\" data-max-num-pages=\"0\" data-next-page=\"2\">\n\t\t<div class=\"edgtf-pl-inner edgtf-outer-space edgtf-owl-slider edgtf-list-is-slider clearfix\">\n\t\t<article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5891 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-frango portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/chowmein_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCHOW MEIN AUX 3 D\u00c9LICES\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 2h25min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/chow-mein-tres-delicias\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5933 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-frango portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/codorniz_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">CAILLE AU CIDRE<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 2h45min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/codorniz-com-sidra\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6083 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-carne portfolio-tag-frango portfolio-tag-legumes portfolio-tag-pato portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/frango-ameijoa-thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPOULET ET PALOURDES \u00c0 LA MODE DE L\u2019ALGARVE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 60min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/frango-com-ameijoas-a-algarvia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6095 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-frango portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pato portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/frango-camarao-leitecoco_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">POULET AUX CREVETTES<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plat principal | 55min | 4 personnes<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/fr\/portfolio-item\/frango-com-camaroes\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>EMBALLAGE:<\/strong> Saco 1kg<\/p>\n<p>Ideal para o seu prato de bacalhau ou bife \u00e0 Portuguesa.<\/p>","protected":false},"featured_media":11124,"template":"","meta":[],"product_brand":[],"product_cat":[923],"product_tag":[383,929],"class_list":{"0":"post-11123","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-batatas","7":"product_tag-batatas","8":"product_tag-rodela","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product\/11123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/media\/11124"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/media?parent=11123"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product_brand?post=11123"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product_cat?post=11123"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/product_tag?post=11123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}