{"id":10812,"date":"2023-06-06T14:35:15","date_gmt":"2023-06-06T14:35:15","guid":{"rendered":"https:\/\/www.frijobel.pt\/?p=10812"},"modified":"2023-06-06T14:37:50","modified_gmt":"2023-06-06T14:37:50","slug":"frijobel-promove-campanha-solidaria-de-recolha-de-sangue","status":"publish","type":"post","link":"https:\/\/frijobel.pt\/fr\/frijobel-promove-campanha-solidaria-de-recolha-de-sangue\/","title":{"rendered":"FRIJOBEL PROMOVE CAMPANHA SOLID\u00c1RIA DE RECOLHA DE SANGUE"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-equal-height vc_row-flex\" ><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768 edgtf-one-column-alignment-center\" ><div class=\"edgtf-eh-item  edgtf-vertical-alignment-top edgtf-horizontal-alignment-center \"  data-item-class=\"edgtf-eh-custom-1553\" data-1367-1600=\"0px 5% 0 5%\" data-1025-1366=\"0px 5% 0 5%\"   >\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-1553\" >\n\t\t\t<div class=\"edgtf-image-gallery  edgtf-ig-slider-type edgtf-three-columns edgtf-huge-space  edgtf-image-behavior-lightbox\">\n\t<div class=\"edgtf-ig-slider edgtf-owl-slider\" data-number-of-items=\"1\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-slider-padding=\"no\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"edgtf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"edgtf-ig-lightbox edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2023\/06\/Design-sem-nome.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-235]\" title=\"Design sem nome\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2023\/06\/Design-sem-nome.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2023\/06\/Design-sem-nome.jpg 550w, https:\/\/frijobel.pt\/wp-content\/uploads\/2023\/06\/Design-sem-nome-300x276.jpg 300w, https:\/\/frijobel.pt\/wp-content\/uploads\/2023\/06\/Design-sem-nome-13x12.jpg 13w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768 \" ><div class=\"edgtf-eh-item    \"  data-item-class=\"edgtf-eh-custom-2823\" data-1367-1600=\"-10px 5% 0 5%\" data-1025-1366=\"-10px 5% 0 5%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-2823\" style=\"padding: 0 0 0 0\">\n\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>A Frijobel, em parceria com o Instituto Portugu\u00eas do Sangue e da Transplanta\u00e7\u00e3o (IPST), promoveu com sucesso uma campanha solid\u00e1ria de doa\u00e7\u00e3o de sangue, resultando numa impressionante contribui\u00e7\u00e3o de cerca de 20 litros de sangue. O evento contou com a participa\u00e7\u00e3o de 34 colaboradores empenhados em ajudar a comunidade e salvar vidas.<\/p>\n<p>A campanha solid\u00e1ria realizada nas instala\u00e7\u00f5es da Frijobel, em Penela, teve como objetivo consciencializar sobre a import\u00e2ncia da doa\u00e7\u00e3o de sangue e incentivar a participa\u00e7\u00e3o ativa dos colaboradores em a\u00e7\u00f5es de responsabilidade social. Desde o in\u00edcio da campanha que os colaboradores da Frijobel demonstraram coragem e interesse ao dedicarem parte do seu tempo a salvar vidas, tendo sido uma atitude muito elogiada por parte da equipa m\u00e9dica do IPST, destacando a sua contribui\u00e7\u00e3o significativa para o abastecimento do banco de sangue nacional.<\/p>\n<p>O resultado da campanha foi extremamente gratificante, uma vez que foi recolhida uma quantidade significativa de sangue que far\u00e1 a diferen\u00e7a na vida de in\u00fameras pessoas que dependem de transfus\u00f5es sangu\u00edneas para sobreviver. Pedro Vasconcelos, presidente do<br \/>\nconselho de administra\u00e7\u00e3o, expressou a sua gratid\u00e3o e orgulho pela dedica\u00e7\u00e3o dos colaboradores em apoiar esta causa humanit\u00e1ria \u201cA nossa equipa tem um esp\u00edrito solid\u00e1rio excecional\u201d, afirmou. \u201cEsta a\u00e7\u00e3o refor\u00e7a o nosso compromisso com a responsabilidade social e o<br \/>\nbem-estar da comunidade em que estamos inseridos. Estamos verdadeiramente felizes em fazer a diferen\u00e7a\u201d.<\/p>\n<p>\u00c9 de notar que a Frijobel j\u00e1 esteve envolvida em a\u00e7\u00f5es de cariz sociais anteriores a esta recolha, como foi o caso do refor\u00e7o de refei\u00e7\u00e3o noturna a pessoas em situa\u00e7\u00e3o de sem-abrigo, pobreza e exclus\u00e3o social. Mais recentemente foi tamb\u00e9m realizada a recolha de bens de primeira necessidade que foram posteriormente entregues a uma associa\u00e7\u00e3o local \u201cO Ninho da Mariazinha\u201d.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Aumento da Capacidade Log\u00edstica da Frijobel.<\/p>","protected":false},"author":20,"featured_media":10814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[892,496,888,896,479],"tags":[893,891,824,878],"class_list":["post-10812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-35-anos","category-estrutura","category-eventos","category-feiras","category-noticias","tag-35-anos","tag-comida-para-a-vida","tag-frijobel","tag-frozen-food"],"_links":{"self":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/posts\/10812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/comments?post=10812"}],"version-history":[{"count":1,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/posts\/10812\/revisions"}],"predecessor-version":[{"id":10813,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/posts\/10812\/revisions\/10813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/media\/10814"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/media?parent=10812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/categories?post=10812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frijobel.pt\/fr\/wp-json\/wp\/v2\/tags?post=10812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}