{"id":5329,"date":"2020-11-19T08:52:25","date_gmt":"2020-11-19T08:52:25","guid":{"rendered":"http:\/\/www.frijobel.pt\/novo\/?post_type=product&#038;p=5329"},"modified":"2021-02-04T23:20:42","modified_gmt":"2021-02-04T23:20:42","slug":"alho-frances","status":"publish","type":"product","link":"https:\/\/frijobel.pt\/es\/product\/alho-frances\/","title":{"rendered":"AJO PUERRO"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"edgtf-row-grid-section-wrapper\"  style=\"background-color:#ffffff\"><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1607213685508 vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-7050\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-7050\" style=\"padding: 3% 0 0 2%\">\n\t\t\t<div class=\"edgtf-portfolio-slider-holder\"><div class=\"edgtf-portfolio-list-holder edgtf-grid-list edgtf-disable-bottom-space edgtf-pl-gallery edgtf-four-columns edgtf-tiny-space edgtf-pl-standard-tilt    edgtf-pl-pag-no-pagination    edgtf-pl-info-skin-light edgtf-pag-below-slider  light\"  data-type=\"gallery\" data-number-of-columns=\"four\" data-space-between-items=\"tiny\" data-number-of-items=\"-1\" data-image-proportions=\"square\" data-enable-fixed-proportions=\"no\" data-enable-image-shadow=\"no\" data-category=\"receitas-frijobel\" data-tag=\"legumes\" data-orderby=\"title\" data-order=\"ASC\" data-item-style=\"standard-tilt\" data-enable-title=\"yes\" data-title-tag=\"h4\" data-title-text-transform=\"uppercase\" data-enable-category=\"no\" data-enable-count-images=\"yes\" data-enable-excerpt=\"yes\" data-excerpt-length=\"65\" data-pagination-type=\"no-pagination\" data-filter=\"no\" data-filter-order-by=\"name\" data-enable-article-animation=\"no\" data-portfolio-slider-on=\"yes\" data-enable-fullheight=\"no\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"yes\" data-pagination-skin=\"light\" data-info-skin=\"light\" data-pagination-position=\"below-slider\" data-max-num-pages=\"0\" data-next-page=\"2\">\n\t\t<div class=\"edgtf-pl-inner edgtf-outer-space edgtf-owl-slider edgtf-list-is-slider clearfix\">\n\t\t<article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-3844 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-pescado portfolio-tag-postas portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/08\/abrotea_posta_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"Posta de Abrota com batata thumbs\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tBR\u00d3TOLA CON PATATAS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 6h30min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/abrotea-batatinha\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-3876 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-pescado portfolio-tag-prato-principal portfolio-tag-receitas\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/08\/atum_grelhado_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"Atum Grelhado com feij\u00e3o thumb\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tAT\u00daN A LA PLANCHA CON SALSA GIOVANA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 1h40min | 2 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/atum-grelhado-molho\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6722 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-bacalhau portfolio-tag-legumes portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/bacalhau_de_sonho_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">BACALAO FRITO AL HORNO<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 1h25min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/bacalhau-de-sonho\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5136 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-caldeirada portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/caldeirada_de_peixe2-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCALDERETA DE PESCADO Y LANGOSTINOS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 50 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/caldeirada-peixe-camaroes-black-tiger\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5836 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-cebola portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/cataplana_chocos-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">CATAPLANA DE SEPIA<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 1h50min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/cataplana-de-chocos\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5845 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/cataplana_tamboril_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">CATAPLANA DE RAPE<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 1h50min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/cataplana-de-tamboril\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5856 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/choco-lagareiro_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSEPIA \u00abLAGAREIRO\u00bb\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 1h30min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/choco-a-lagareiro\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5875 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/choco-assado_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSEPIA ASADA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 2h30min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/choco-assado\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5880 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/choco-frito_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tChoco Frito\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 2h25min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/choco-frito\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5909 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/chowsen-lulas_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCHOW MEIN DE CALAMARES\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 40 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/chow-mein-de-lulas\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5891 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-frango portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/chowmein_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tCHOW MEIN MIT 3 DELIKATESSEN\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 2h25min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/chow-mein-tres-delicias\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-5973 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-pescado portfolio-tag-raia portfolio-tag-sopa\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/ensopado_raia_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tGUISO DE RAYA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Sopa | 45min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/ensopado-de-raia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6015 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-delicias portfolio-tag-legumes portfolio-tag-pescado portfolio-tag-posta portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/estufado-redfish_thumbz-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tESTOFADO DE GALLINETA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 25 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/estufado-de-red-fish\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6026 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-feijao portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/feijoada-camarao-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFABADA DE LANGOSTINOS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 30 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/feijoada-de-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6036 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-feijao portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/feijoada-chocos-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">FABADA DE SEPIA<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 25 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/feijoada-de-choco\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6043 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/feijoada-choco-camarao_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFABADA DE SEPIA CON GAMBAS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 35 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/feijoada-de-choco-e-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6054 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-feijao portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/feijoada-peixe-camarao_thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tFABADA DE\u00a0PESCADO Y MARISCO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 50 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/feijoada-de-peixe-e-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6083 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-carne portfolio-tag-frango portfolio-tag-legumes portfolio-tag-pato portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/frango-ameijoa-thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPOLLO CON\u00a0ALMEJAS A LA ALGARV\u00cdA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 60 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/frango-com-ameijoas-a-algarvia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6095 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-carnes portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-frango portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pato portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/frango-camarao-leitecoco_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">POLLO CON\u00a0LANGOSTINOS<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 55 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/frango-com-camaroes\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6104 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/gratinado-marisco-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tGRATINADO DE MARISCO CON AJO PUERRO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 45 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/gratinado-de-marisco-e-alho-frances\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6115 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/rejardineira-chocos_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tENSALADILLA DE SEPIA CON LANGOSTINOS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 35 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/jardineira-de-choco-e-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6125 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-sopa\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/korma-camarao_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tKORMA DE LANGOSTINOS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Sopa | 45min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/korma-de-camarao-com-garam-massala\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6156 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/maruca-exotico_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tMARUCA CON SALSA EX\u00d3TICA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 50 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/maruca-com-molho-exotico\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6176 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/massada-chocos-camaroes_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPASTA CON SEPIA Y LANGOSTINOS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 30 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/massada-de-chocos-com-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6186 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/massada-marisco-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPASTA DE MARISCO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 20 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/massada-de-marisco-tradicional\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6194 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-entrada portfolio-tag-legumes\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/mexilhoes-a-francesa-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tMEJILLONES A LA FRANCESA\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Entrada | 20 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/mexilhoes-a-francesa\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6202 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-caldeirada portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/moqueca-de-peixe_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\t\u00abMOQUECA\u00bb DE PESCADO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 55 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/moqueca-de-peixe\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6209 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-pescado portfolio-tag-prato-principal portfolio-tag-pre-cozinhado\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/panado-de-peixe_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPESCADO EMPANADO CON QUESO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 1h20min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/panado-de-peixe-com-queijo\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6231 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-bivalves portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pescado portfolio-tag-posta portfolio-tag-prato-principal portfolio-tag-tomate\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/peixe-estufado_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPESCADO ESTOFADO CON ALMEJAS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 55 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/peixe-estufado-com-ameijoas\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6291 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/polvo-coentrada_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPULPO CON CILANTRO\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 2h30min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/polvo-de-coentrada\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6300 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/polvo-de-natal_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPULPO DE NAVIDAD\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 1h10min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/polvo-de-natal\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6309 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-cefalopodes portfolio-tag-legumes portfolio-tag-polvo portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/polvo-espargos_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tPULPO SALTEADO CON ESP\u00c1RRAGOS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 1h10min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/polvo-salteado-com-espargos\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6330 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-camarao-black-tiger portfolio-tag-delicias portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-pimento portfolio-tag-prato-principal portfolio-tag-pre-cozinhado portfolio-tag-sapateira\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/quinoa-marisco_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tQUINOA CON MARISCO Y MINI PIMIENTOS\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 35 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/quinoa-com-marisco-e-mini-pimentos\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6339 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-pescado portfolio-tag-posta portfolio-tag-prato-principal portfolio-tag-raia\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/raia-forno-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tRAYA AL HORNO CON ACEITE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 35 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/raia-no-forno-em-azeite-dalho\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6357 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-delicias portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-prato-principal portfolio-tag-sapateira\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/risotto-sapateira_thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">RISOTTO DE BUEY DE MAR<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 55 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/risotto-de-sapateira\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6382 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-camarao portfolio-tag-cogumelos portfolio-tag-entradas portfolio-tag-legumes portfolio-tag-marisco portfolio-tag-salada\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/salada-morna_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">SALADA TEMPLADA DE LANGOSTINOS<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Ensalada | 1h10min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/salada-morna-de-camarao\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6369 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-pescado portfolio-tag-prato-principal portfolio-tag-salmao\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/salmao-com-mel_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">SALM\u00d3N CON MIEL<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 2h20min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/salmao-com-mel\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6630 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato portfolio-tag-principal portfolio-tag-sardinha portfolio-tag-tomate\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sardinha_tomatada_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSARDINAS CON TOMATE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 2h20min | 2 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/sardinhas-de-tomatada\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6640 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato portfolio-tag-principal portfolio-tag-sardinha portfolio-tag-tomate\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sardinha_panada_tumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">SARDINAS EMPANADAS<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 1h30min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/sardinhas-panadas\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6713 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-bacalhau portfolio-tag-legumes portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/tiborna-bacalhau_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\"><span class=\"edgtf-st-title-bold\">TIBORNA<\/span> <span class=\"edgtf-st-title-bold\">DE<\/span> <span class=\"edgtf-st-title-bold\">BACALAO<\/span><\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 45 min | 4 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/tiborna-de-bacalhau\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6733 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-pescado portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-legumes portfolio-tag-maruca portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/tornedo-maruca-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tTOURNED\u00d3 DE MARUCA CON BACON\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Plato principal | 2h15min | 3 personas<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/es\/portfolio-item\/tornedo-de-maruca-com-bacon\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>ENVASE: <\/strong>Bolsa<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":5330,"template":"","meta":[],"product_brand":[],"product_cat":[284],"product_tag":[548,321,317,320,318],"class_list":{"0":"post-5329","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-legumes","7":"product_tag-alho-frances","8":"product_tag-hortalica","9":"product_tag-legumes","10":"product_tag-vegetables","11":"product_tag-vegetais","13":"first","14":"instock","15":"shipping-taxable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/product\/5329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/media\/5330"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/media?parent=5329"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/product_brand?post=5329"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/product_cat?post=5329"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/product_tag?post=5329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}