{"id":6476,"date":"2020-12-01T09:22:33","date_gmt":"2020-12-01T09:22:33","guid":{"rendered":"http:\/\/www.frijobel.pt\/novo\/?page_id=6476"},"modified":"2023-07-27T14:09:22","modified_gmt":"2023-07-27T14:09:22","slug":"politica-de-privacidade","status":"publish","type":"page","link":"https:\/\/frijobel.pt\/es\/politica-de-privacidade\/","title":{"rendered":"POL\u00cdTICA DE PRIVACIDAD"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"edgtf-row-grid-section-wrapper\"  ><div class=\"edgtf-row-grid-section\"><div data-edgtf-anchor=\"fale-connosco-form-contact\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1605305659092 vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item   edgtf-horizontal-alignment-center\"  data-item-class=\"edgtf-eh-custom-7539\" data-1367-1600=\"5% 3% 5% 3%\" data-1025-1366=\"5% 3% 5% 3%\" data-769-1024=\"5% 3% 5% 3%\" data-681-768=\"5% 3% 5% 3%\" data-680=\"5% 3% 5% 3%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-7539\" style=\"padding: 5% 3% 5% 3%\">\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-center edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title\" style=\"color: #494949\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">POL\u00cdTICA DE<\/span> <span class=\"edgtf-st-title-light\">DE<\/span> PRIVACIDAD\t\t\t<\/h2>\n\t\t\t\t\t\t\t<p class=\"edgtf-st-text\" >\n\t\t\t\tRESPETAMOS TUS DATOS\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"edgtf-elements-holder  edgtf-eh-full-height edgtf-one-column  edgtf-responsive-mode-768 edgtf-one-column-alignment-left\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-8738\" data-1367-1600=\"3% 2% 3% 2%\" data-1025-1366=\"3% 2% 3% 2%\" data-769-1024=\"3% 2% 3% 2%\" data-681-768=\"3% 2% 3% 2%\" data-680=\"3% 2% 3% 2%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-8738\" style=\"padding: 3% 0 3% 0\">\n\t\t\t<div class=\"edgtf-accordion-holder edgtf-ac-default  edgtf-accordion edgtf-ac-simple  clearfix\">\n\t<h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">QUI\u00c9NES SOMOS?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Fundada en 1988, Frijobel se orgulla de ser una empresa familiar, con ra\u00edces en la regi\u00f3n centro de Portugal, cerca de la ciudad de Coimbra, en la hist\u00f3rica villa de Penela.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Frijobel es una sociedad an\u00f3nima, cuyo capital social pertenece a la familia Vasconcelos, que se dedica a la actividad industrial de procesamiento de pescado y a la comercializaci\u00f3n de productos alimenticios, como pescado, marisco, precocinados, verduras y postres.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Considerando su amplia experiencia y presencia en el mercado, Frijobel es una empresa con indicadores financieros excelentes, cuya operaci\u00f3n se ha ido extendiendo, a lo largo del tiempo, a un contexto global.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">POR QU\u00c9 ESTA POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS PERSONALES<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Esta Pol\u00edtica pretende informar a los clientes\/proveedores\/usuarios de Frijobel sobre las reglas generales de privacidad y tratamiento de datos personales, que se recogen y tratan respetando y cumpliendo de forma rigurosa las disposiciones de la legislaci\u00f3n de protecci\u00f3n de datos personales, en particular el Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016 (\u00abRGPD\u00bb).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Frijobel respeta las mejores pr\u00e1cticas en el \u00e1rea de la seguridad y la protecci\u00f3n de los datos personales, para lo que ha adoptado las medidas t\u00e9cnicas y organizativas necesarias al cumplimiento del RGPD y para garantizar que el tratamiento de los datos personales es l\u00edcito, leal, transparente y limitado a los fines autorizados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Frijobel est\u00e1 comprometida con la protecci\u00f3n y confidencialidad de los datos personales, para lo que ha adoptado las medidas que considera adecuadas para garantizar la exactitud, integridad y confidencialidad de los datos personales, as\u00ed como todos los dem\u00e1s derechos de los interesados correspondientes.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">QU\u00c9 INCLUYE LA PRESENTE POL\u00cdTICA?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">La presente Pol\u00edtica se aplica exclusivamente a la recogida y al tratamiento de los datos personales por los que Frijobel es responsable, en el \u00e1mbito de los servicios y productos ofrecidos a sus clientes\/usuarios, y en todas las situaciones en las que se traten datos personales.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">QU\u00c9 SON DATOS PERSONALES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Datos personales son toda la informaci\u00f3n, de cualquier tipo e independientemente de su soporte, incluidos sonido e imagen, que se refiera a una persona f\u00edsica identificada o identificable.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se considera identificable una persona f\u00edsica cuya identidad pueda determinarse, directa o indirectamente, en particular mediante un nombre, un n\u00famero de identificaci\u00f3n, datos de localizaci\u00f3n, identificadores en l\u00ednea o uno o varios elementos propios de la identidad f\u00edsica, fisiol\u00f3gica, gen\u00e9tica, ps\u00edquica, econ\u00f3mica, cultural o social de dicha persona.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">EN QU\u00c9 CONSISTE EL TRATAMIENTO DE DATOS PERSONALES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">El tratamiento de datos personales consiste en una operaci\u00f3n o conjunto de operaciones realizadas sobre datos personales o conjuntos de datos personales, a trav\u00e9s de procedimientos automatizados o no, como la recogida, registro, organizaci\u00f3n, estructuraci\u00f3n, conservaci\u00f3n, adaptaci\u00f3n, recuperaci\u00f3n, consulta, utilizaci\u00f3n, comunicaci\u00f3n, difusi\u00f3n, cotejo, interconexi\u00f3n, limitaci\u00f3n, supresi\u00f3n o destrucci\u00f3n.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">QUI\u00c9N ES EL RESPONSABLE DEL TRATAMIENTO DE LOS DATOS?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">La entidad responsable del tratamiento de los datos personales es Frijobel, que determina los fines y medios del tratamiento de los mismos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A este efecto, en el caso de que el interesado tenga que ponerse en contacto con el responsable del tratamiento de los datos, podr\u00e1 hacerlo a trav\u00e9s de los medios y de los contactos indicados a continuaci\u00f3n: <\/span><a href=\"mailto:dados.pessoais@frijobel.pt\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">dados.pessoais@frijobel.pt<\/span><\/a><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">CU\u00c1LES SON LOS TIPOS DE DATOS PERSONALES TRATADOS?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel, en el \u00e1mbito de las actividades que desarrolla, procede al tratamiento de los datos personales necesarios a la prestaci\u00f3n de servicios y\/o al suministro de productos, as\u00ed como en el \u00e1mbito de la relaci\u00f3n comercial con proveedores, tratando datos como el nombre, la direcci\u00f3n, el n\u00famero de tel\u00e9fono y la direcci\u00f3n de correo electr\u00f3nico, seg\u00fan la informaci\u00f3n facilitada por los interesados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los datos personales tambi\u00e9n se podr\u00e1n tratar para fines de marketing o comunicaci\u00f3n de ofertas de bienes o servicios de Frijobel, en los casos en los que el interesado lo haya autorizado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si existe el consentimiento previo del interesado, este puede retirarse a cualquier momento, sin que se comprometa la legalidad del tratamiento efectuado con base en el consentimiento previamente prestado.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">CU\u00c1NDO Y C\u00d3MO RECOGEMOS TUS DATOS PERSONALES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel recoge tus datos personales a trav\u00e9s del tel\u00e9fono, por escrito o de su sitio web, garantizando el previo consentimiento del interesado, siempre que sea necesario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunos datos personales son indispensables a la ejecuci\u00f3n del contrato y sin ellos Frijobel no podr\u00e1 suministrar un determinado producto o servicio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el caso de que el interesado no sea cliente\/proveedor\/usuario de Frijobel, sus datos personales solo se tratar\u00e1n cuando se faciliten, y en este caso se aplicar\u00e1n las normas de esta Pol\u00edtica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los datos personales recogidos se pueden tratar inform\u00e1ticamente y de forma automatizada o no automatizada, garantizando siempre el riguroso cumplimiento de la legislaci\u00f3n de protecci\u00f3n de datos personales, y se almacenar\u00e1n en bases de datos espec\u00edficas, creadas a este efecto y, en ninguna circunstancia, los datos recogidos se usar\u00e1n para otro fin que no sea aquel para el que se han recogido o para el que el interesado haya prestado su consentimiento.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">QUI\u00c9NES SON LOS DESTINATARIOS DE LOS DATOS PERSONALES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Sin perjuicio de los destinatarios mencionados en esta Pol\u00edtica, Frijobel podr\u00e1 comunicar los datos personales del cliente\/proveedor\/usuario, con el fin de cumplimiento de obligaciones legales, a autoridades policiales, judiciales, fiscales y reguladoras.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">CU\u00c1LES SON LOS FINES DEL TRATAMIENTO DE LOS DATOS PERSONALES Y LOS FUNDAMENTOS JUR\u00cdDICOS CORRESPONDIENTES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Em geral, os dados pessoais recolhidos t\u00eam como fundamento e destinam-se \u00e0 gest\u00e3o da rela\u00e7\u00e3o contratual e comercial, \u00e0 presta\u00e7\u00e3o dos servi\u00e7os contratados, \u00e0 adequa\u00e7\u00e3o dos servi\u00e7os, \u00e0s necessidades e interesses do Cliente\/Fornecedor\/Utilizador, nomeadamente para efeitos de acesso a funcionalidades espec\u00edficas dos servi\u00e7os, a a\u00e7\u00f5es de informa\u00e7\u00e3o e marketing.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adicionalmente, los datos personales tambi\u00e9n se podr\u00e1n tratar a efectos de cumplimiento de obligaciones legales.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">DURANTE CU\u00c1NTO TIEMPO SE CONSERVAN LOS DATOS PERSONALES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">El plazo durante el que se almacenan y se conservan los datos personales es diferente seg\u00fan el fin para el que se trata la informaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Efectivamente, existen requisitos legales que obligan a conservar los datos por un plazo m\u00ednimo. As\u00ed, y siempre que no exista una exigencia legal espec\u00edfica, los datos se almacenar\u00e1n y conservar\u00e1n solo durante el plazo m\u00ednimo necesario a la realizaci\u00f3n de los fines que han llevado a su recogida o a su posterior tratamiento, seg\u00fan lo definido en la ley.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">CU\u00c1LES SON TUS DERECHOS COMO INTERESADO?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Enquanto titulares dos dados pessoais, \u00e9 garantido aos Clientes\/Fornecedores\/Utilizadores, a qualquer momento, o direito de acesso, retifica\u00e7\u00e3o, atualiza\u00e7\u00e3o, limita\u00e7\u00e3o e elimina\u00e7\u00e3o dos seus dados pessoais (salvo quanto aos dados que s\u00e3o indispens\u00e1veis \u00e0 presta\u00e7\u00e3o dos servi\u00e7os pela Frijobel ou ao cumprimento de obriga\u00e7\u00f5es legais a que o respons\u00e1vel pelo tratamento esteja sujeito), o direito de oposi\u00e7\u00e3o \u00e0 utiliza\u00e7\u00e3o dos mesmos para fins comerciais pela Frijobel e \u00e0 retirada do consentimento, sem que tal comprometa a licitude do tratamento efetuado ao abrigo desse consentimento, bem como o direito \u00e0 portabilidade dos dados.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">CU\u00c1LES SON LAS MEDIDAS ADOPTADAS POR FRIJOBEL PARA GARANTIZAR LA SEGURIDAD DE LOS DATOS PERSONALES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel asume el compromiso de garantizar la protecci\u00f3n de la seguridad de los datos personales que se le facilitan, para lo que ha aprobado e implementado rigurosas normas a este respecto. El cumplimiento de estas reglas es una obligaci\u00f3n de todos aquellos que acceden legalmente a los mismos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Teniendo en cuenta la preocupaci\u00f3n y el empe\u00f1o que Frijobel revela en la defensa de los datos personales, se han adoptado diversas medidas de seguridad, de car\u00e1cter t\u00e9cnico y organizativo, a fin de proteger los datos personales que se le facilitan, para evitar su difusi\u00f3n, p\u00e9rdida, uso indebido, modificaci\u00f3n, tratamiento o acceso no autorizado, as\u00ed como cualquier otra forma de tratamiento il\u00edcito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, las entidades terceras que, en el contexto de prestaciones de servicios, procedan al tratamiento de datos personales del cliente\/proveedor\/usuario en nombre y por cuenta de Frijobel, est\u00e1n obligadas, por escrito, a ejecutar las medidas t\u00e9cnicas y de seguridad adecuadas que, a cada momento, satisfagan los requisitos previstos en la legislaci\u00f3n vigente y aseguren la defensa de los derechos del interesado (en particular, la protecci\u00f3n de la privacidad y de los datos personales).<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">C\u00d3MO PUEDES ACCEDER, RECTIFICAR, ACTUALIZAR, LIMITAR, BORRAR U OPONERTE AL TRATAMIENTO DE TUS DATOS, O ELIMINAR TU CONSENTIMIENTO?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Sin perjuicio de lo dispuesto en el RGPD, el interesado puede hacerlo directamente o a trav\u00e9s de escrito enviado al responsable del tratamiento correspondiente, a trav\u00e9s de los contactos disponibles a este efecto en el presente documento, as\u00ed como de los dem\u00e1s contactos facilitados por Frijobel.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">C\u00d3MO PUEDES OPONERTE A LA RECEPCI\u00d3N DE CONTACTOS CON FINES DE MARKETING?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel puede enviar acciones de divulgaci\u00f3n a sus clientes\/proveedores\/usuarios de nuevos productos o servicios, por ejemplo, a trav\u00e9s del tel\u00e9fono, correo electr\u00f3nico, SMS o cualquier otro servicio de comunicaciones electr\u00f3nicas, en el caso de que el interesado haya prestado el consentimiento correspondiente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si el interesado no desea seguir recibiendo estas comunicaciones puede, a cualquier momento, retirar su consentimiento al uso de sus datos con fines de marketing.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">EN QU\u00c9 CIRCUNSTANCIAS EXISTE COMUNICACI\u00d3N DE DATOS A OTRAS ENTIDADES (TERCEROS Y SUBCONTRATADOS)?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel, en el desarrollo de su actividad, puede solicitar a terceros la prestaci\u00f3n de determinados servicios. A veces, la prestaci\u00f3n de estos servicios supone el acceso, por parte de estas entidades, a datos personales de los clientes\/proveedores\/usuarios. Cuando esto sucede, Frijobel toma las medidas adecuadas para garantizar que las entidades que tienen acceso a los datos son reconocidas y ofrecen las m\u00e1s elevadas garant\u00edas a este nivel, lo que se considera debidamente previsto y establecido contractualmente entre Frijobel y estas terceras entidades.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As\u00ed, todas las entidades subcontratadas por Frijobel tratar\u00e1n los datos personales de nuestros clientes\/proveedores\/usuarios en nombre y por cuenta de Frijobel, adoptando las medidas t\u00e9cnicas y organizativas necesarias para proteger los datos personales y evitar la destrucci\u00f3n, accidental o il\u00edcita, la p\u00e9rdida accidental, la modificaci\u00f3n, difusi\u00f3n o el acceso no autorizado y cualquier otro modo de tratamiento il\u00edcito\u00a0autorizado y cualquier otra forma de tratamiento il\u00edcito.\u00a0En cualquiera de estos casos, Frijobel sigue siendo responsable de los datos personales que se le faciliten. <\/span><span style=\"font-weight: 400;\">autorizado e contra qualquer outra forma de tratamento il\u00edcito. <\/span><span style=\"font-weight: 400;\">Em qualquer dos casos, a Frijobel permanece respons\u00e1vel pelos dados pessoais que lhe sejam disponibilizados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">EN QU\u00c9 CIRCUNSTANCIAS TRANSFERIMOS TUS DATOS PERSONALES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">La prestaci\u00f3n de determinados servicios por Frijobel puede suponer la transferencia de tus datos fuera de Portugal, incluso fuera de la Uni\u00f3n Europea o a Organizaciones Internacionales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este caso, Frijobel cumplir\u00e1 rigurosamente las disposiciones legales aplicables, por ejemplo, sobre la determinaci\u00f3n de la adecuaci\u00f3n de los pa\u00edses de destino en lo que se refiere a la protecci\u00f3n de datos personales y a los requisitos aplicables a estas transferencias, incluidos, siempre que se aplique, la celebraci\u00f3n de los instrumentos contractuales oportunos que garanticen y respeten las exigencias legales vigentes.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">C\u00d3MO PUEDO CONOCER LOS POSIBLES CAMBIOS A ESTA POL\u00cdTICA DE PROTECCI\u00d3N DE DATOS PERSONALES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">\u201cCookies\u201d son peque\u00f1as etiquetas de software que se almacenan en el ordenador a trav\u00e9s del navegador (browser) y que solo almacenan informaci\u00f3n sobre las preferencias, por lo que no incluyen los datos personales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para saber m\u00e1s sobre cookies y c\u00f3mo las usa Frijobel en su sitio web, consulta el siguiente documento Sobre Cookies: <a href=\"https:\/\/frijobel.pt\/es\/website_96915706\/cookie-policy\/\">https:\/\/frijobel.pt\/website_96915706\/cookie-policy\/\u00a0<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">C\u00d3MO PUEDO CONOCER LOS POSIBLES CAMBIOS A ESTA POL\u00cdTICA DE PROTECCI\u00d3N DE DATOS PERSONALES?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel se reserva el derecho de, a cualquier momento, reajustar o modificar la presente Pol\u00edtica de protecci\u00f3n de datos personales.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"edgtf-row-grid-section-wrapper\"  ><div class=\"edgtf-row-grid-section\"><div data-edgtf-anchor=\"fale-connosco-form-contact\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1605305659092 vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item   edgtf-horizontal-alignment-center\"  data-item-class=\"edgtf-eh-custom-3500\" data-1367-1600=\"3% 3% 7% 3%\" data-1025-1366=\"3% 3% 7% 3%\" data-769-1024=\"3% 3% 7% 3%\" data-681-768=\"3% 3% 7% 3%\" data-680=\"3% 3% 7% 3%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-3500\" style=\"padding: 3% 3% 7% 3%\">\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-center edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title\" style=\"color: #494949\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">HABLA<\/span> <span class=\"edgtf-st-title-light\">CON NOSOTROS<\/span>\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"edgtf-elements-holder  edgtf-eh-full-height edgtf-one-column  edgtf-responsive-mode-768 edgtf-one-column-alignment-left\" ><div class=\"edgtf-eh-item   edgtf-horizontal-alignment-center\"  data-item-class=\"edgtf-eh-custom-9825\" data-1367-1600=\"3% 2% 3% 2%\" data-1025-1366=\"3% 2% 3% 2%\" data-769-1024=\"3% 2% 3% 2%\" data-681-768=\"3% 2% 3% 2%\" data-680=\"3% 2% 3% 2%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-9825\" style=\"padding: 3% 0 3% 0\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4895-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"4895\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/6476#wpcf7-f4895-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/6476#wpcf7-f4895-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4895\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4895-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"edgtf-contact\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"NOMBRE\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ASSUNTO\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"ASSUNTO\"><option value=\"SELECIONE UM ASSUNTO\">SELECCIONE UN TEMA<\/option><option value=\"Sugest\u00f5es\">Sugest\u00f5es<\/option><option value=\"Pedido de Informa\u00e7\u00e3o\">Pedido de Informa\u00e7\u00e3o<\/option><option value=\"Candidatura Espont\u00e2nea\">Candidatura Espont\u00e2nea<\/option><option value=\"Reclama\u00e7\u00f5es\">Reclama\u00e7\u00f5es<\/option><option value=\"Outros\">Outros<\/option><\/select><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"MENSAJE\" name=\"your-message\"><\/textarea><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ANEXAR\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.png,.tiff,.pdf,.doc,.docx\" aria-invalid=\"false\" type=\"file\" name=\"ANEXAR\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"privacidade\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacidade\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Acepto la <a href=\"https:\/\/frijobel.pt\/es\/website_96915706\/politica-de-privacidade\/\" target=\"blank\">Pol\u00edtica de privacidad.<\/a>.<\/span><\/label><\/span><\/span><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVIAR\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-edgtf-anchor=\"onde-estamos\" class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-middle vc_row-flex\" style=\"background-color:#ee8829\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-sm vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768 edgtf-one-column-alignment-center\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-5806\" data-1367-1600=\"5% 0 4% 5%\" data-1025-1366=\"5% 0 4% 5%\" data-769-1024=\"5% 0 4% 5%\" data-681-768=\"5% 0 4% 5%\" data-680=\"5% 0 4% 5%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-5806\" style=\"padding: 5% 0 4% 5%\">\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-left edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title\" style=\"color: #ffffff\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">D\u00d3NDE<\/span> <span class=\"edgtf-st-title-light\">ESTAMOS?<\/span>\t\t\t<\/h2>\n\t\t\t\t\t\t\t<p class=\"edgtf-st-text\" style=\"color: #ffffff;font-size: 16px;font-weight: 700\">\n\t\t\t\tPORTUGAL\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-map-pin\" style=\"color: #ffffff;font-size: 20px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">Espinheiro 3230-231 PENELA<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-mobile\" style=\"color: #ffffff;font-size: 23px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">+351 239 569 222<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-print\" style=\"color: #ffffff;font-size: 23px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">+351 239 569 333<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-envelope\" style=\"color: #ffffff;font-size: 20px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">FRIJOBEL@FRIJOBEL.PT<\/p>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-lg vc_hidden-md\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column edgtf-ehi-float edgtf-responsive-mode-1024 edgtf-one-column-alignment-left\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-9430\" data-1367-1600=\"5% 0 4% 5%\" data-1025-1366=\"5% 0 4% 5%\" data-769-1024=\"5% 0 4% 5%\" data-681-768=\"5% 0 4% 5%\" data-680=\"5% 0 4% 5%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-9430\" style=\"padding: 5% 0 4% 5%\">\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-left edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title\" style=\"color: #ffffff\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">D\u00d3NDE<\/span> <span class=\"edgtf-st-title-light\">ESTAMOS?<\/span>\t\t\t<\/h2>\n\t\t\t\t\t\t\t<p class=\"edgtf-st-text\" style=\"color: #ffffff;font-size: 16px;font-weight: 700\">\n\t\t\t\tPORTUGAL\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-map-pin\" style=\"color: #ffffff;font-size: 20px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">Apartado 34 | Espinheiro 3230-231 PENELA<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-mobile\" style=\"color: #ffffff;font-size: 23px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">+351 239 569 222<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-print\" style=\"color: #ffffff;font-size: 23px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">+351 239 569 333<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-envelope\" style=\"color: #ffffff;font-size: 20px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">FRIJOBEL@FRIJOBEL.PT<\/p>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_gmaps_widget wpb_content_element vc_map_responsive\"><div class=\"wpb_wrapper\"><div class=\"wpb_map_wraper\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3055.035560364623!2d-8.413678584615788!3d40.029985479411856!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd22f491383d8c0b%3A0xf68188966d68dbf7!2sFRIJOBEL%20S.A.!5e0!3m2!1sen!2spt!4v1614200303172!5m2!1sen!2spt\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"POL\u00cdTICA DE PRIVACIDADE RESPEITAMOS OS SEUS DADOS QUEM SOMOS? Fundada em 1988, a Frijobel orgulha-se de ser uma empresa familiar com ra\u00edzes na Regi\u00e3o Centro de Portugal, junto \u00e0 cidade de Coimbra, na Vila Hist\u00f3rica de Penela. A Frijobel \u00e9 [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-6476","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/pages\/6476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/comments?post=6476"}],"version-history":[{"count":4,"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/pages\/6476\/revisions"}],"predecessor-version":[{"id":10891,"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/pages\/6476\/revisions\/10891"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/es\/wp-json\/wp\/v2\/media?parent=6476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}