{"id":3642,"date":"2020-07-16T13:23:20","date_gmt":"2020-07-16T13:23:20","guid":{"rendered":"http:\/\/www.frijobel.pt\/novo\/?post_type=product&#038;p=3642"},"modified":"2020-12-06T14:26:29","modified_gmt":"2020-12-06T14:26:29","slug":"sardinha","status":"publish","type":"product","link":"https:\/\/frijobel.pt\/en\/product\/sardinha\/","title":{"rendered":"SARDINE"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"edgtf-row-grid-section-wrapper\"  style=\"background-color:#ffffff\"><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1607264740168 vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-5929\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-5929\" style=\"padding: 3% 0 0 2%\">\n\t\t\t<div class=\"edgtf-portfolio-slider-holder\"><div class=\"edgtf-portfolio-list-holder edgtf-grid-list edgtf-disable-bottom-space edgtf-pl-gallery edgtf-four-columns edgtf-tiny-space edgtf-pl-standard-tilt    edgtf-pl-pag-no-pagination    edgtf-pl-info-skin-light edgtf-pag-below-slider  light\"  data-type=\"gallery\" data-number-of-columns=\"four\" data-space-between-items=\"tiny\" data-number-of-items=\"-1\" data-image-proportions=\"square\" data-enable-fixed-proportions=\"no\" data-enable-image-shadow=\"no\" data-category=\"receitas-frijobel\" data-selected-projects=\"6618,6630,6640,6253,6263\" data-orderby=\"title\" data-order=\"ASC\" data-item-style=\"standard-tilt\" data-enable-title=\"yes\" data-title-tag=\"h4\" data-title-text-transform=\"uppercase\" data-enable-category=\"no\" data-enable-count-images=\"yes\" data-enable-excerpt=\"yes\" data-excerpt-length=\"65\" data-pagination-type=\"no-pagination\" data-filter=\"no\" data-filter-order-by=\"name\" data-enable-article-animation=\"no\" data-portfolio-slider-on=\"yes\" data-enable-fullheight=\"no\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"yes\" data-pagination-skin=\"light\" data-info-skin=\"light\" data-pagination-position=\"below-slider\" data-max-num-pages=\"0\" data-next-page=\"2\">\n\t\t<div class=\"edgtf-pl-inner edgtf-outer-space edgtf-owl-slider edgtf-list-is-slider clearfix\">\n\t\t<article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6253 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/petinga-migas-thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\"><span class=\"edgtf-st-title-bold\">SMALL SARDINES<\/span> <span class=\"edgtf-st-title-bold\">AND<\/span> <span class=\"edgtf-st-title-bold\">CORN<\/span>BREAD<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Main Course | 50min | 4 people<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/en\/portfolio-item\/petinga-com-migas-de-broa\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6263 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-carne portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato-principal\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/11\/petinga-no-forno_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSMALL SARDINES BAKED WITH BACON\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Main Course | 1h25min | 4 people<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/en\/portfolio-item\/petinga-no-forno-com-bacon\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6618 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato portfolio-tag-principal portfolio-tag-sardinha\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sardinha-a-lagareiro_thumb-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">LAGAREIRO-STYLE SARDINES<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Main Course | 2h30min | 4 people<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/en\/portfolio-item\/sardinhas-a-lagareiro\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6630 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato portfolio-tag-principal portfolio-tag-sardinha portfolio-tag-tomate\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sardinha_tomatada_thumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" style=\"text-transform: uppercase\">\n\t\tSARDINES IN TOMATO SAUCE\t<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Main Course | 2h20min | 2 people<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/en\/portfolio-item\/sardinhas-de-tomatada\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-small post-6640 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-marisco portfolio-category-receitas-frijobel portfolio-tag-legumes portfolio-tag-peixe-inteiro portfolio-tag-pescado portfolio-tag-prato portfolio-tag-principal portfolio-tag-sardinha portfolio-tag-tomate\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"506\" src=\"https:\/\/frijobel.pt\/wp-content\/uploads\/2020\/12\/sardinha_panada_tumbs-550x506.jpg\" class=\"attachment-kenozoik_edge_image_square size-kenozoik_edge_image_square wp-post-image\" alt=\"\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title translation-block\" style=\"text-transform: uppercase\">BREADED SARDINES<\/h4>\n\n\t\t\t\n\t\t\t\n\t\t\t\t<p itemprop=\"description\" class=\"edgtf-pli-excerpt\">Main Course | 1h30min | 4 people<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/frijobel.pt\/en\/portfolio-item\/sardinhas-panadas\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>SCIENTIFIC NAME: <\/strong>Sardina pilchardus<br \/>\n<strong>ORIGIN: <\/strong> Northeast Atlantic, FAO 27<br \/>\n<strong>GRADING CODE:<\/strong> 10 &#8211; 12<br \/>\nF<strong>ORMAT:<\/strong> Whole<br \/>\n<strong>PACKAGING:<\/strong> Bag, Bulk<\/p>\n<p>&nbsp;<\/p>\n<p>see map<\/p>","protected":false},"featured_media":3481,"template":"","meta":[],"product_brand":[],"product_cat":[282],"product_tag":[340,418],"class_list":{"0":"post-3642","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pescado","7":"product_tag-peixe-inteiro","8":"product_tag-sardinha","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/frijobel.pt\/en\/wp-json\/wp\/v2\/product\/3642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/frijobel.pt\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/en\/wp-json\/wp\/v2\/media\/3481"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/en\/wp-json\/wp\/v2\/media?parent=3642"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/frijobel.pt\/en\/wp-json\/wp\/v2\/product_brand?post=3642"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/frijobel.pt\/en\/wp-json\/wp\/v2\/product_cat?post=3642"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/frijobel.pt\/en\/wp-json\/wp\/v2\/product_tag?post=3642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}