{"id":6476,"date":"2020-12-01T09:22:33","date_gmt":"2020-12-01T09:22:33","guid":{"rendered":"http:\/\/www.frijobel.pt\/novo\/?page_id=6476"},"modified":"2023-07-27T14:09:22","modified_gmt":"2023-07-27T14:09:22","slug":"politica-de-privacidade","status":"publish","type":"page","link":"https:\/\/frijobel.pt\/de\/politica-de-privacidade\/","title":{"rendered":"DATENSCHUTZRICHTLINIE"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"edgtf-row-grid-section-wrapper\"  ><div class=\"edgtf-row-grid-section\"><div data-edgtf-anchor=\"fale-connosco-form-contact\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1605305659092 vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item   edgtf-horizontal-alignment-center\"  data-item-class=\"edgtf-eh-custom-3536\" data-1367-1600=\"5% 3% 5% 3%\" data-1025-1366=\"5% 3% 5% 3%\" data-769-1024=\"5% 3% 5% 3%\" data-681-768=\"5% 3% 5% 3%\" data-680=\"5% 3% 5% 3%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-3536\" style=\"padding: 5% 3% 5% 3%\">\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-center edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title\" style=\"color: #494949\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">POL\u00cdTICA<\/span> <span class=\"edgtf-st-title-light\">DE<\/span> DATENSCHUTZRICHTLINIE\t\t\t<\/h2>\n\t\t\t\t\t\t\t<p class=\"edgtf-st-text\" >\n\t\t\t\tWIR SCH\u00dcTZEN IHRE DATEN\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"edgtf-elements-holder  edgtf-eh-full-height edgtf-one-column  edgtf-responsive-mode-768 edgtf-one-column-alignment-left\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-8091\" data-1367-1600=\"3% 2% 3% 2%\" data-1025-1366=\"3% 2% 3% 2%\" data-769-1024=\"3% 2% 3% 2%\" data-681-768=\"3% 2% 3% 2%\" data-680=\"3% 2% 3% 2%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-8091\" style=\"padding: 3% 0 3% 0\">\n\t\t\t<div class=\"edgtf-accordion-holder edgtf-ac-default  edgtf-accordion edgtf-ac-simple  clearfix\">\n\t<h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WER SIND WIR?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel wurde 1988 gegr\u00fcndet und ist stolz darauf, ein Familienunternehmen mit Wurzeln im Zentrum Portugals nahe der Stadt Coimbra im historischen Dorf Penela zu sein.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Frijobel ist eine Aktiengesellschaft, deren Aktienkapital der Familie Vasconcelos geh\u00f6rt. Der Unternehmenszweck ist die industriellen Verarbeitung von Fisch sowie die Herstellung und der Verkauf von Tiefk\u00fchlprodukten aus Fisch, Meeresfr\u00fcchten, Fertiggerichten, Gem\u00fcse und S\u00fc\u00dfspeisen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aufgrund seiner gro\u00dfen Erfahrung und Pr\u00e4senz auf dem Markt ist Frijobel ein Unternehmen mit hervorragenden Finanzzahlen. Im Laufe der Zeit konnte das Unternehmen Gesch\u00e4ftsbeziehungen in alle Welt kn\u00fcpfen.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WARUM SCH\u00dcTZT DIE DATENSCHUTZRICHTLINIE PERSONENBEZOGENE DATEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Diese Richtlinie soll Kunden\/Lieferanten\/Nutzer von Frijobel auf die allgemeinen Regeln zum Schutz der Privatsph\u00e4re und den Umgang mit personenbezogenen Daten aufmerksam machen. Sie wurde unter strikter Beachtung und Einhaltung der Bestimmungen der jeweils geltenden Rechtsvorschriften zum Schutz personenbezogener Daten erstellt und richtet sich insbesondere nach der EU-Verordnung 2016\/679 des Europ\u00e4ischen Parlaments und des Rates vom 27. April 2016 (\u201eDSGVO\u201c).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Frijobel respektiert die Best Practices im Bereich der Sicherheit und des Schutzes personenbezogener Daten und hat zu diesem Zweck die erforderlichen technischen und organisatorischen Ma\u00dfnahmen ergriffen, um die DSGVO einzuhalten und sicherzustellen, dass die Verarbeitung personenbezogener Daten rechtm\u00e4\u00dfig, fair und transparent ist und nur f\u00fcr autorisierte Zwecke gilt.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Zum Schutz personenbezogener Daten und zur Wahrung ihrer Vertraulichkeit verpflichtet sich Frijobel nach dem Ergreifen angemessener Ma\u00dfnahmen, die Richtigkeit, Integrit\u00e4t und Vertraulichkeit personenbezogener Daten und aller \u00fcbrigen Rechte der jeweiligen Inhaber zu gew\u00e4hrleisten.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WAS BEINHALTET DIESE DATENSCHUTZRICHTLINIE?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Diese Richtlinie gilt ausschlie\u00dflich f\u00fcr die Erhebung und Verarbeitung personenbezogener Daten, f\u00fcr die Frijobel im Rahmen der Dienstleistungen und Produkte, die seinen Kunden\/Nutzern zur Verf\u00fcgung gestellt werden, verantwortlich ist, und sie gilt auch f\u00fcr Situationen, in denen die Verarbeitung personenbezogener Daten erfolgt.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WAS SIND PERSONENBEZOGENE DATEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Personenbezogene Daten sind Informationen aller Art und unabh\u00e4ngig vom Datentr\u00e4ger (Ton und Bild), die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person beziehen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Eine identifizierbare Person ist eine Person, die direkt oder indirekt unter Bezugnahme auf einen Namen, eine Identifikationsnummer, Standortdaten, elektronische Identifikatoren oder auf ein oder mehrere Elemente, welche auf ihre physische, physiologische, genetische Identit\u00e4t oder ihre geistige, wirtschaftliche, kulturelle oder soziale Situation verweisen, identifizierbar ist.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WAS UMFASST DIE AUFBEREITUNG VON PERSONENBEZOGENEN DATEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Die Verarbeitung personenbezogener Daten besteht aus einer Operation oder einer Reihe von Vorg\u00e4ngen, die mit personenbezogenen Daten oder einem Datensatz unter Verwendung automatisierter\/nicht automatisierter Mittel, durchgef\u00fchrt werden und umfasst die Sammlung, Registrierung, Organisation, Strukturierung, Speicherung, Anpassung, Wiederherstellung, Abfrage, Verwendung, Offenlegung, Verbreitung, Vergleich, Zusammenschaltung, Einschr\u00e4nkung, L\u00f6schung oder Zerst\u00f6rung von Daten.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WER IST F\u00dcR DIE DATENVERARBEITUNG VERANTWORTLICH?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Die f\u00fcr die Verarbeitung personenbezogener Daten verantwortliche Stelle ist das Unternehmen Frijobel, das die Zwecke und Mittel der Datenverarbeitung festlegt.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Zu diesem Zweck hat der Inhaber der personenbezogenen Daten, wenn er den f\u00fcr die Datenverarbeitung Verantwortlichen kontaktieren will die M\u00f6glichkeit, eine E-Mail an folgende E-Mail-Adresse zu senden: <\/span><a href=\"mailto:dados.pessoais@frijobel.pt\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">dados.pessoais@frijobel.pt<\/span><\/a><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WELCHE PERSONENBEZOGENEN DATEN WERDEN VERARBEITET?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel verarbeitet im Rahmen seiner Aktivit\u00e4ten die f\u00fcr die Erbringung von Dienstleistungen und\/oder die Lieferung von Produkten erforderlichen personenbezogenen Daten, ebenso die im Rahmen der Gesch\u00e4ftsbeziehung mit Lieferanten erhobenen Daten wie Name, Adresse, Telefonnummer und E-Mail-Adresse, welche vom Inhaber der personenbezogener Daten angegeben werden.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Personenbezogene Daten k\u00f6nnen auch zum Zweck der Vermarktung oder Verbreitung von Waren- oder Dienstleistungsangeboten von Frijobel verarbeitet werden, sofern der jeweilige Inhaber der Daten diese Zwecke genehmigt hat.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Eine fr\u00fchere Zustimmung des Inhabers kann jederzeit widerrufen werden, ohne dass die Rechtm\u00e4\u00dfigkeit einer zuvor erteilten Zustimmung zur Datenverarbeitung beeintr\u00e4chtigt wird.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WANN UND WIE SAMMELN WIR PERSONENBEZOGENE DATEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel sammelt Ihre personenbezogenen Daten telefonisch, schriftlich und \u00fcber seine Webseite und garantiert, sofern erforderlich, dass der Inhaber der personenbezogenen Daten die M\u00f6glichkeit erh\u00e4lt, seine Zustimmung vor der Verarbeitung seiner Daten abzugeben.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Einige personenbezogene Daten sind f\u00fcr die Vertragserf\u00fcllung unabdingbar, da Frijobel ohne diese Daten das betreffende Produkt nicht liefern oder die Dienstleistung nicht erbringen kann.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Wenn der Inhaber der personenbezogenen Daten kein Kunde\/Lieferant\/Nutzer von Frijobel ist, werden seine personenbezogenen Daten erst verarbeitet, wenn sie zur Verf\u00fcgung gestellt werden. In diesem Fall gelten die Regeln dieser Richtlinie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die erhobenen personenbezogenen Daten k\u00f6nnen computergest\u00fctzt, automatisiert oder nicht automatisiert verarbeitet werden, wobei in jedem Fall die strikte Einhaltung der Rechtsvorschriften zum Schutz personenbezogener Daten gew\u00e4hrleistet ist und diese in bestimmten Datenbanken, welche zu diesem Zweck eingerichtet worden sind, gespeichert werden. Unter keinen Umst\u00e4nden werden die erhobenen Daten f\u00fcr einen anderen Zweck als den, f\u00fcr den sie erhoben wurden oder f\u00fcr den der Inhaber seine Zustimmung erteilt hat, verwendet.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WER SIND DIE EMPF\u00c4NGER VON PERSONENBEZOGENEN DATEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Ungeachtet der in dieser Richtlinie angegebenen Empf\u00e4nger kann Frijobel die personenbezogenen Daten des Kunden\/Lieferanten\/Nutzers zum Zwecke der Einhaltung gesetzlicher Verpflichtungen, insbesondere gegen\u00fcber Polizei, Justiz, Finanzamt und Aufsichtsbeh\u00f6rden, weitergeben.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WAS SIND DIE ZWECKE DER VERARBEITUNG PERSONENBEZOGENER DATEN UND WELCHES SIND DIE RECHTLICHEN GRUNDLAGEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Em geral, os dados pessoais recolhidos t\u00eam como fundamento e destinam-se \u00e0 gest\u00e3o da rela\u00e7\u00e3o contratual e comercial, \u00e0 presta\u00e7\u00e3o dos servi\u00e7os contratados, \u00e0 adequa\u00e7\u00e3o dos servi\u00e7os, \u00e0s necessidades e interesses do Cliente\/Fornecedor\/Utilizador, nomeadamente para efeitos de acesso a funcionalidades espec\u00edficas dos servi\u00e7os, a a\u00e7\u00f5es de informa\u00e7\u00e3o e marketing.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dar\u00fcber hinaus k\u00f6nnen personenbezogene Daten auch zur Erf\u00fcllung gesetzlicher Verpflichtungen verarbeitet werden.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WIE LANGE BEWAHREN WIR IHRE PERSONENBEZOGENEN DATEN AUF?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Der Zeitraum, in dem personenbezogene Daten aufbewahrt und gespeichert werden, h\u00e4ngt vom Zweck ab, f\u00fcr den die Informationen verarbeitet werden.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tats\u00e4chlich gibt es gesetzliche Vorschriften, die angeben, f\u00fcr welchen Mindestzeitraum die Daten aufbewahrt werden m\u00fcssen. Daher werden die Daten, wenn keine besonderen gesetzlichen Vorschriften bestehen, nur f\u00fcr den Mindestzeitraum, der f\u00fcr die Verfolgung der Zwecke, f\u00fcr die sie erhoben oder gem\u00e4\u00df den gesetzlich festgelegten Bedingungen aufbereitet wurden, gespeichert und aufbewahrt.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WELCHE RECHTE HABEN SIE ALS INHABER?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Enquanto titulares dos dados pessoais, \u00e9 garantido aos Clientes\/Fornecedores\/Utilizadores, a qualquer momento, o direito de acesso, retifica\u00e7\u00e3o, atualiza\u00e7\u00e3o, limita\u00e7\u00e3o e elimina\u00e7\u00e3o dos seus dados pessoais (salvo quanto aos dados que s\u00e3o indispens\u00e1veis \u00e0 presta\u00e7\u00e3o dos servi\u00e7os pela Frijobel ou ao cumprimento de obriga\u00e7\u00f5es legais a que o respons\u00e1vel pelo tratamento esteja sujeito), o direito de oposi\u00e7\u00e3o \u00e0 utiliza\u00e7\u00e3o dos mesmos para fins comerciais pela Frijobel e \u00e0 retirada do consentimento, sem que tal comprometa a licitude do tratamento efetuado ao abrigo desse consentimento, bem como o direito \u00e0 portabilidade dos dados.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WELCHE MASSNAHMEN ERGREIFT FRIJOBEL, UM DIE SICHERHEIT IHRER PERSONENBEZOGENEN DATEN ZU GEW\u00c4HRLEISTEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel verpflichtet sich, den Schutz und die Sicherheit der zur Verf\u00fcgung gestellten personenbezogenen Daten zu gew\u00e4hrleisten, und hat zu diesem Zweck strenge Regeln erlassen und umgesetzt. Die Einhaltung dieser Regeln ist eine Verpflichtung f\u00fcr alle, die legal auf die Daten zugreifen d\u00fcrfen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In Anbetracht der Besorgnis und des Engagements von Frijobel zum Schutz personenbezogener Daten wurden verschiedene technische und organisatorische Sicherheitsma\u00dfnahmen getroffen, um die zur Verf\u00fcgung gestellten personenbezogenen Daten vor Verbreitung, Verlust, Missbrauch, \u00c4nderung, unbefugter Aufbereitung\/Verwendung oder anderen Formen rechtswidriger Aufbereitung zu sch\u00fctzen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dar\u00fcber hinaus werden Dritte, die im Rahmen einer Dienstleistung die personenbezogenen Daten des Kunden\/Lieferanten\/Nutzers namens und im Auftrag von Frijobel verarbeiten, schriftlich verpflichtet, entsprechende technische und sicherheitstechnische Ma\u00dfnahmen zu ergreifen, die jederzeit die gesetzlichen Anforderungen erf\u00fcllen und den Schutz der Rechte des Dateninhabers (n\u00e4mlich den Schutz der Privatsph\u00e4re und der personenbezogenen Daten) gew\u00e4hrleisten.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WIE K\u00d6NNEN SIE AUF IHRE PERSONENBEZOGENEN DATEN ZUGREIFEN, SIE KORRIGIEREN, AKTUALISIEREN, EINSCHR\u00c4NKEN, L\u00d6SCHEN, DER VERARBEITUNG WIDERSPRECHEN ODER IHRE ZUSTIMMUNG ZUR\u00dcCKNEHMEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Ungeachtet der Bestimmungen der DSGVO kann der Inhaber personenbezogener Daten direkt oder auf schriftlichen Antrag, welcher an die f\u00fcr die Datenverarbeitung verantwortliche Person zu richten ist, \u00fcber die von Frijobel zur Verf\u00fcgung gestellten Kontaktadressen Kontakt aufnehmen.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WIE K\u00d6NNEN SIE SICH DER ZUSENDUNG VON KONTAKTANGABEN F\u00dcR MARKETINGZWECKE WIDERSETZEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel kann seine Kunden\/Lieferanten\/Nutzer \u00fcber die Verbreitung neuer Produkte oder Dienstleistungen per Telefon, E-Mail, SMS oder ein anderes elektronisches Medium informieren, wenn der Inhaber der personenbezogenen Daten die entsprechende Zustimmung erteilt hat.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Wenn der Inhaber personenbezogener Daten nicht gewillt ist, diese Mitteilungen weiterhin zu erhalten, kann er seine Zustimmung zur Verwendung seiner Daten f\u00fcr Marketingzwecke jederzeit widerrufen.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">ZU WELCHEN GELEGENHEITEN WERDEN DATEN MIT ANDEREN UNTERNEHMEN (DRITTEN ODER SUBUNTERNEHMERN) AUSGETAUSCHT?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel kann im Rahmen seiner T\u00e4tigkeit Dritte zur Erbringung bestimmter Dienstleistungen beauftragen. Manchmal impliziert die Erbringung dieser Dienstleistungen den Zugriff dieser Stellen auf personenbezogene Daten von Kunden\/Lieferanten\/Nutzern. In diesem Fall ergreift Frijobel die entsprechenden Ma\u00dfnahmen, um sicherzustellen, dass Unternehmen, die Zugriff auf die Daten haben, seri\u00f6s sind und auf dieser Ebene die h\u00f6chsten Anforderungen, die Frijobel mit Dritten ordnungsgem\u00e4\u00df vereinbart und vertraglich sch\u00fctzt, erf\u00fcllen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Daher wird jedes von Frijobel beauftragte Subunternehmen personenbezogene Daten unserer Kunden\/Lieferanten\/Nutzer namens und im Auftrag von Frijobel vorschriftsm\u00e4\u00dfig aufbereiten und die erforderlichen technischen und organisatorischen Ma\u00dfnahmen ergreifen, um personenbezogene Daten vor Zerst\u00f6rung, versehentlichem, rechtswidrigem oder zuf\u00e4lligem Verlust, vor \u00c4nderung, Verbreitung oder unbefugtem Zugriff zu sch\u00fctzen und andere Formen der rechtswidrigen Aufbereitung unterlassen.\u00a0In jedem Fall haftet Frijobel f\u00fcr die zur Verf\u00fcgung gestellten personenbezogenen Daten. <\/span><span style=\"font-weight: 400;\">autorizado e contra qualquer outra forma de tratamento il\u00edcito. <\/span><span style=\"font-weight: 400;\">Em qualquer dos casos, a Frijobel permanece respons\u00e1vel pelos dados pessoais que lhe sejam disponibilizados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">IN WELCHEN SITUATIONEN \u00dcBERTRAGEN WIR IHRE PERSONENBEZOGENEN DATEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Die Erbringung bestimmter Dienstleistungen durch Frijobel kann bedeuten, dass Ihre Daten in andere L\u00e4nder, auch L\u00e4nder au\u00dferhalb der Europ\u00e4ischen Union oder auf internationale Organisationen \u00fcbertragen werden.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In diesem Fall wird Frijobel die geltenden gesetzlichen Bestimmungen strikt einhalten und im Hinblick auf die Feststellung der Eignung des Ziellandes (der Ziell\u00e4nder) in Bezug auf den Schutz personenbezogener Daten und der f\u00fcr die Daten\u00fcbermittlung geltenden Anforderungen, Vertr\u00e4ge abschlie\u00dfen, die die Einhaltung der gesetzlichen Vorschriften garantieren.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WIE K\u00d6NNEN SIE \u00c4NDERUNGEN AN DER DATENSCHUTZRICHTLINIE \u00dcBER DEN SCHUTZ PERSONENBEZOGENER DATEN IN ERFAHRUNG BRINGEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">\"Cookies\" sind kleine Software-Tags, die \u00fcber den Browser (Browser) auf dem Computer gespeichert werden und nur Informationen aufnehmen, die sich auf Ihre Pr\u00e4ferenzen beziehen, jedoch keine personenbezogenen Daten \u00fcbermitteln.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Weitere Informationen \u00fcber Cookies und deren Verwendung durch Frijobel auf seiner Webseite finden Sie im folgenden Dokument \u00fcber Cookies: <a href=\"https:\/\/frijobel.pt\/de\/website_96915706\/cookie-policy\/\">https:\/\/frijobel.pt\/website_96915706\/cookie-policy\/\u00a0<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><h4 class=\"edgtf-accordion-title\">\n\t<span class=\"edgtf-tab-title\">WIE K\u00d6NNEN SIE \u00c4NDERUNGEN AN DER DATENSCHUTZRICHTLINIE \u00dcBER DEN SCHUTZ PERSONENBEZOGENER DATEN IN ERFAHRUNG BRINGEN?<\/span>\n    <span class=\"edgtf-accordion-mark\">\n\t\t<span class=\"edgtf_icon_plus fas fa-chevron-down\"><\/span>\n\t\t<span class=\"edgtf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"edgtf-accordion-content\">\n\t<div class=\"edgtf-accordion-content-inner\">\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"font-weight: 400;\">Frijobel beh\u00e4lt sich das Recht vor, jederzeit Anpassungen oder \u00c4nderungen an dieser Datenschutzrichtlinie vorzunehmen.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"edgtf-row-grid-section-wrapper\"  ><div class=\"edgtf-row-grid-section\"><div data-edgtf-anchor=\"fale-connosco-form-contact\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1605305659092 vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item   edgtf-horizontal-alignment-center\"  data-item-class=\"edgtf-eh-custom-8506\" data-1367-1600=\"3% 3% 7% 3%\" data-1025-1366=\"3% 3% 7% 3%\" data-769-1024=\"3% 3% 7% 3%\" data-681-768=\"3% 3% 7% 3%\" data-680=\"3% 3% 7% 3%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-8506\" style=\"padding: 3% 3% 7% 3%\">\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-center edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title\" style=\"color: #494949\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">SPRECHEN SIE MIT UNS<\/span> <span class=\"edgtf-st-title-light\">CONNOSCO<\/span>\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"edgtf-elements-holder  edgtf-eh-full-height edgtf-one-column  edgtf-responsive-mode-768 edgtf-one-column-alignment-left\" ><div class=\"edgtf-eh-item   edgtf-horizontal-alignment-center\"  data-item-class=\"edgtf-eh-custom-1744\" data-1367-1600=\"3% 2% 3% 2%\" data-1025-1366=\"3% 2% 3% 2%\" data-769-1024=\"3% 2% 3% 2%\" data-681-768=\"3% 2% 3% 2%\" data-680=\"3% 2% 3% 2%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-1744\" style=\"padding: 3% 0 3% 0\">\n\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4895-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"4895\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/6476#wpcf7-f4895-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/de\/wp-json\/wp\/v2\/pages\/6476#wpcf7-f4895-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4895\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4895-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"edgtf-contact\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"NAME\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ASSUNTO\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"ASSUNTO\"><option value=\"SELECIONE UM ASSUNTO\">W\u00c4HLE EIN THEMA AUS<\/option><option value=\"Sugest\u00f5es\">Sugest\u00f5es<\/option><option value=\"Pedido de Informa\u00e7\u00e3o\">Pedido de Informa\u00e7\u00e3o<\/option><option value=\"Candidatura Espont\u00e2nea\">Candidatura Espont\u00e2nea<\/option><option value=\"Reclama\u00e7\u00f5es\">Reclama\u00e7\u00f5es<\/option><option value=\"Outros\">Outros<\/option><\/select><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"MITTEILUNG\" name=\"your-message\"><\/textarea><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ANEXAR\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.png,.tiff,.pdf,.doc,.docx\" aria-invalid=\"false\" type=\"file\" name=\"ANEXAR\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"privacidade\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacidade\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ich akzeptiere <a href=\"https:\/\/frijobel.pt\/de\/website_96915706\/politica-de-privacidade\/\" target=\"blank\">Datenschutzrichtlinie.<\/a>.<\/span><\/label><\/span><\/span><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"SENDEN\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-edgtf-anchor=\"onde-estamos\" class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-middle vc_row-flex\" style=\"background-color:#ee8829\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-sm vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768 edgtf-one-column-alignment-center\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-9797\" data-1367-1600=\"5% 0 4% 5%\" data-1025-1366=\"5% 0 4% 5%\" data-769-1024=\"5% 0 4% 5%\" data-681-768=\"5% 0 4% 5%\" data-680=\"5% 0 4% 5%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-9797\" style=\"padding: 5% 0 4% 5%\">\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-left edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title\" style=\"color: #ffffff\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">WO<\/span> <span class=\"edgtf-st-title-light\">SIND WIR?<\/span>\t\t\t<\/h2>\n\t\t\t\t\t\t\t<p class=\"edgtf-st-text\" style=\"color: #ffffff;font-size: 16px;font-weight: 700\">\n\t\t\t\tPORTUGAL\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-map-pin\" style=\"color: #ffffff;font-size: 20px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">Espinheiro 3230-231 PENELA<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-mobile\" style=\"color: #ffffff;font-size: 23px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">+351 239 569 222<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-print\" style=\"color: #ffffff;font-size: 23px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">+351 239 569 333<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-envelope\" style=\"color: #ffffff;font-size: 20px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">FRIJOBEL@FRIJOBEL.PT<\/p>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-lg vc_hidden-md\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder   edgtf-one-column edgtf-ehi-float edgtf-responsive-mode-1024 edgtf-one-column-alignment-left\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-2348\" data-1367-1600=\"5% 0 4% 5%\" data-1025-1366=\"5% 0 4% 5%\" data-769-1024=\"5% 0 4% 5%\" data-681-768=\"5% 0 4% 5%\" data-680=\"5% 0 4% 5%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-2348\" style=\"padding: 5% 0 4% 5%\">\n\t\t\t<div class=\"edgtf-section-title-holder  edgtf-st-standard edgtf-st-left edgtf-st-normal-space\" >\n\t<div class=\"edgtf-st-inner\">\n\t\t\t\t\t<h2 class=\"edgtf-st-title\" style=\"color: #ffffff\">\n\t\t\t\t<span class=\"edgtf-st-title-bold\">WO<\/span> <span class=\"edgtf-st-title-light\">SIND WIR?<\/span>\t\t\t<\/h2>\n\t\t\t\t\t\t\t<p class=\"edgtf-st-text\" style=\"color: #ffffff;font-size: 16px;font-weight: 700\">\n\t\t\t\tPORTUGAL\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-map-pin\" style=\"color: #ffffff;font-size: 20px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">Apartado 34 | Espinheiro 3230-231 PENELA<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-mobile\" style=\"color: #ffffff;font-size: 23px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">+351 239 569 222<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-print\" style=\"color: #ffffff;font-size: 23px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">+351 239 569 333<\/p>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 12px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-icon-list-holder\" >\n\t<div class=\"edgtf-il-icon-holder\">\n\t\t<i class=\"edgtf-icon-font-awesome fa fa-envelope\" style=\"color: #ffffff;font-size: 20px\"><\/i>\t<\/div>\n\t<p class=\"edgtf-il-text\" style=\"color: #ffffff;padding-left: 28px\">FRIJOBEL@FRIJOBEL.PT<\/p>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_gmaps_widget wpb_content_element vc_map_responsive\"><div class=\"wpb_wrapper\"><div class=\"wpb_map_wraper\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3055.035560364623!2d-8.413678584615788!3d40.029985479411856!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd22f491383d8c0b%3A0xf68188966d68dbf7!2sFRIJOBEL%20S.A.!5e0!3m2!1sen!2spt!4v1614200303172!5m2!1sen!2spt\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"POL\u00cdTICA DE PRIVACIDADE RESPEITAMOS OS SEUS DADOS QUEM SOMOS? Fundada em 1988, a Frijobel orgulha-se de ser uma empresa familiar com ra\u00edzes na Regi\u00e3o Centro de Portugal, junto \u00e0 cidade de Coimbra, na Vila Hist\u00f3rica de Penela. A Frijobel \u00e9 [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-6476","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/frijobel.pt\/de\/wp-json\/wp\/v2\/pages\/6476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frijobel.pt\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/frijobel.pt\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frijobel.pt\/de\/wp-json\/wp\/v2\/comments?post=6476"}],"version-history":[{"count":4,"href":"https:\/\/frijobel.pt\/de\/wp-json\/wp\/v2\/pages\/6476\/revisions"}],"predecessor-version":[{"id":10891,"href":"https:\/\/frijobel.pt\/de\/wp-json\/wp\/v2\/pages\/6476\/revisions\/10891"}],"wp:attachment":[{"href":"https:\/\/frijobel.pt\/de\/wp-json\/wp\/v2\/media?parent=6476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}